{"id":46780,"date":"2022-12-12T17:20:07","date_gmt":"2022-12-12T20:20:07","guid":{"rendered":"https:\/\/guarai.to.gov.br\/portal\/?p=46780"},"modified":"2022-12-12T17:20:10","modified_gmt":"2022-12-12T20:20:10","slug":"edicao-ordinaria-1-507-de-12-de-dezembro-de-2022","status":"publish","type":"post","link":"https:\/\/guarai.to.gov.br\/portal\/2022\/12\/12\/edicao-ordinaria-1-507-de-12-de-dezembro-de-2022\/","title":{"rendered":"Edi\u00e7\u00e3o Ordin\u00e1ria 1.507 de 12 de dezembro de 2022"},"content":{"rendered":"<a href=\"https:\/\/guarai.to.gov.br\/portal\/wp-content\/uploads\/2022\/12\/DOM-1507.pdf\" class=\"pdfemb-viewer\" style=\"width:1200px;height:1500px;\" data-width=\"1200\" data-height=\"1500\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">DOM-1507<\/a>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n\n\n\n<p><a href=\"http:\/\/LEI N\u00ba 788 - DE 12 DE DEZEMBRO DE 2022  \u201cINSTITUI O DIA MUNICIPAL DA CONSCIENTIZA\u00c7\u00c3O DO AUTISMO NO MUNIC\u00cdPIO DE GUARA\u00cd \u2013TO\u201d    FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVOU, e eu, Prefeita Municipal, no uso de minhas atribui\u00e7\u00f5es legais, SANCIONO a seguinte Lei:  Art. 1\u00ba Fica institu\u00eddo o Dia Municipal da Conscientiza\u00e7\u00e3o do Autismo, a ser realizado, anualmente, no dia 02 de abril.  Art. 2\u00ba A Data objetiva a realiza\u00e7\u00e3o de eventos e atividades, voltada para a promo\u00e7\u00e3o e a conscientiza\u00e7\u00e3o dos Direitos dos Autistas.  Par\u00e1grafo \u00danico: Fica sugerido que a Secretaria de Sa\u00fade seja a incentivadora de proporcionar estes eventos e divulga\u00e7\u00f5es para os alunos e comunidade em geral;  I -Semin\u00e1rios II- Divulga\u00e7\u00e3o em meios de comunica\u00e7\u00e3o do munic\u00edpio III- Palestras para comunidade em geral IV-Murais V- Panfletagem  Art. 3\u00ba Os eventos e atividades citados no Art. 2\u00ba dever\u00e3o ser realizados nas escolas, Secretarias e demais espa\u00e7os p\u00fablicos do munic\u00edpio.  Art. 4\u00ba Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o, ficando revogado demais disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos 12 (doze) dias do m\u00eas de dezembro do ano de 2022 (dois mil e vinte e dois).  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI N\u00ba 789 - DE 12 DE DEZEMBRO DE 2022.  \u201cAUTORIZA O MUNIC\u00cdPIO DE GUARA\u00cd \u2013 TO, A PARTICIPAR DO CONSORCIO P\u00daBLICO INTERMUNICIPAL PARA O DESENVOLVIMENTO SUSTENT\u00c1VEL DA REGI\u00c3O DO BICO DO PAPAGAIO \u2013 COINBIPA E D\u00c1 OUTRAS PROVID\u00caNCIAS\u201d.  A PREFEITA DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais, faz saber que a C\u00e2mara Municipal APROVA e eu, Prefeita Municipal SANCIONO a seguinte Lei:  Art. 1\u00ba - Fica o Munic\u00edpio de Guara\u00ed \u2013 TO, autorizado a participar do Consorcio P\u00fablico Intermunicipal para o Desenvolvimento Sustent\u00e1vel da Regi\u00e3o do Bico do Papagaio - COINBIPA, ratificando o Estatuto, Protocolo de Inten\u00e7\u00e3o, Contrato de Cons\u00f3rcio P\u00fablico, constitui\u00e7\u00e3o, elei\u00e7\u00e3o e posse da diretoria em exerc\u00edcio.   Par\u00e1grafo \u00danico: A finalidade do cons\u00f3rcio \u00e9 a congrega\u00e7\u00e3o de esfor\u00e7os, visando o planejamento, a coordena\u00e7\u00e3o e a execu\u00e7\u00e3o de atividades de interesse comum dos munic\u00edpios participantes.  Art. 2\u00ba - O estatuto do Consorcio P\u00fablico Intermunicipal para o Desenvolvimento Sustent\u00e1vel da Regi\u00e3o do Bico do Papagaio - COINBIPA dispor\u00e1 sobre diversas \u00e1reas visando o bem comum de seus consorciados.  Art. 3\u00ba - Os entes consorciados poder\u00e3o ceder servidores p\u00fablicos ao Cons\u00f3rcio, na forma e condi\u00e7\u00f5es da legisla\u00e7\u00e3o de cada um.  Art. 4\u00ba - O Poder Executivo Municipal destinando recursos financeiros necess\u00e1rios para o cumprimento do contrato de rateio do Consorcio P\u00fablico Intermunicipal para o Desenvolvimento Sustent\u00e1vel da Regi\u00e3o do Bico do Papagaio - COINBIPA, cujo valor dever\u00e1 ser consignado na Lei Or\u00e7ament\u00e1ria Anual, em conformidade com o disposto no artigo 8\u00ba, da Lei n\u00ba 11.107\/2005 e Decreto n\u00ba 6.017\/2007.  \u00a7 1\u00b0 - Para o exerc\u00edcio financeiro de 2022 o poder executivo est\u00e1 autorizado a criar uma a\u00e7\u00e3o espec\u00edfica no or\u00e7amento vigente (CONTRIBUI\u00c7\u00c3O AO CONS\u00d3RCIO P\u00daBLICO INTERMUNICIPAL \u2013 COINBIPA) vinculada a Secretaria Municipal de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e Habita\u00e7\u00e3o, bem como os elementos de despesas 3.1.71.70: Despesas com pessoal e encargos sociais, 3.3.71.70: Outras despesas correntes, 4.4.71.70: Despesas de Capital. O elemento de despesa ser\u00e1 criado com valor R$ 10.000,00 e posteriormente suplementado conforme autorizado na Lei Or\u00e7ament\u00e1ria.  \u00a7 2\u00b0 - O contrato de rateio ser\u00e1 formalizado em cada exerc\u00edcio financeiro e seu prazo de vig\u00eancia n\u00e3o ser\u00e1 superior ao das dota\u00e7\u00f5es que o suportam, por\u00e9m, ser\u00e1 aditivado o valor sem altera\u00e7\u00e3o, automaticamente, at\u00e9 que se defina novos valores. \u00a7 3\u00b0 - \u00c9 vedada a aplica\u00e7\u00e3o dos recursos entregues por meio de rateio para o atendimento de despesas gen\u00e9ricas, inclusive transfer\u00eancias ou opera\u00e7\u00f5es de cr\u00e9dito.  \u00a7 4\u00b0 - Os entes Consorciados, isolados ou em conjunto, bem como o Cons\u00f3rcio P\u00fablico, s\u00e3o partes leg\u00edtimas para exigir o cumprimento das obriga\u00e7\u00f5es previstas no contrato de rateio.  \u00a7 5\u00b0 - Com o objetivo de permitir o atendimento dos dispositivos da Lei Complementar n\u00ba 101\/00, o Cons\u00f3rcio P\u00fablico deve fornecer as informa\u00e7\u00f5es necess\u00e1rias para que sejam consolidadas, nas contas dos entes Consorciados, todas as despesas realizadas com os recursos entregues em virtude de contrato de rateio, de forma que possam ser contabilizadas nas contas de cada ente Consorciado na conformidade com os elementos econ\u00f4micos e das atividades ou projetos atendidos.  \u00a7 6\u00b0 - Poder\u00e1 ser exclu\u00eddo do Cons\u00f3rcio P\u00fablico, ap\u00f3s pr\u00e9via suspens\u00e3o, o ente Consorciado que n\u00e3o consignar, em nas suas Leis Or\u00e7ament\u00e1rias futuras ou em cr\u00e9ditos adicionais, as dota\u00e7\u00f5es suficientes para suportar as despesas assumidas por meio de contrato de rateio.  Art. 5\u00ba - A retirada do ente Consorciado do Cons\u00f3rcio P\u00fablico depender\u00e1 de ato formal de seu representante na assembleia geral, na forma previamente disciplinada no Protocolo de Inten\u00e7\u00f5es do Consorcio P\u00fablico Intermunicipal para o Desenvolvimento Sustent\u00e1vel da Regi\u00e3o do Bico do Papagaio - COINBIPA.  Par\u00e1grafo \u00danico: Os bens destinados ao Cons\u00f3rcio P\u00fablico pelo Consorciado que se retira somente ser\u00e3o revertidos ou retrocedidos no caso de expressa previs\u00e3o no contrato de cons\u00f3rcio p\u00fablico ou no instrumento de transfer\u00eancia ou aliena\u00e7\u00e3o.  Art. 6\u00ba - A altera\u00e7\u00e3o ou extin\u00e7\u00e3o do Cons\u00f3rcio P\u00fablico depender\u00e1 de instrumento aprovado pela assembleia geral, ratificado mediante lei por todos os entes Consorciados.   Art. 7\u00ba - Aplica-se ao Cons\u00f3rcio P\u00fablico o disposto na Constitui\u00e7\u00e3o Federal, Lei n\u00ba 11.107, de 06 de abril de 2005 e Decreto n\u00ba 6.017\/2007, de 17 de janeiro de 2007.  Art. 8\u00ba - Esta Lei entrar\u00e1 em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos 12 (doze) dias do m\u00eas de dezembro do ano de 2022 (dois mil e vinte e dois).  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI N\u00ba 790\/2022 - DE 12 DE DEZEMBRO DE 2022  \u201cAUTORIZA CONCEDER AUX\u00cdLIO FINANCEIRO MEDIANTE CONV\u00caNIO \u00c0 ASSOCIA\u00c7\u00c3O CASA DO VIRA-LATA, QUE ESPEC\u00cdFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d  FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVOU, e eu, Prefeita Municipal, no uso de minhas atribui\u00e7\u00f5es legais, SANCIONO a seguinte Lei:  Art. 1\u00ba. Fica a Chefe do Poder Executivo Municipal de Guara\u00ed autorizada a conceder aux\u00edlio financeiro, mediante conv\u00eanio, no valor de R$ 24.000,00 (vinte e quatro mil reais) \u00e0 Associa\u00e7\u00e3o Casa do Vira-Lata, entidade sem fins lucrativos, inscrita no CNPJ sob n\u00ba.46.312.023\/0001-32.  Par\u00e1grafo \u00danico: O munic\u00edpio compromete-se a dar todo o suporte veterin\u00e1rio que se fizer necess\u00e1rio aos animais da associa\u00e7\u00e3o, e em parceria com a associa\u00e7\u00e3o compromete-se a realizarem feiras de ado\u00e7\u00e3o periodicamente, buscando adotantes, utilizando ainda de seus canais oficiais para divulga\u00e7\u00e3o dos eventos e animais dispon\u00edveis.  Art. 2\u00ba. O aux\u00edlio financeiro de que trata esta Lei ser\u00e1 concedido em 12 (doze) parcelas de R$ 2.000,00 (dois mil reais) a partir de janeiro de 2022 e ser\u00e1 exclusivamente para manuten\u00e7\u00e3o do abrigo, na aquisi\u00e7\u00e3o de alimenta\u00e7\u00e3o, medicamentos e outras necessidades que possam suprir as car\u00eancias advindas de uma situa\u00e7\u00e3o, mediante regulamenta\u00e7\u00e3o estabelecida em conv\u00eanio a ser celebrado entre as partes.  Par\u00e1grafo \u00danico: A Associa\u00e7\u00e3o fica com o compromisso de, a cada m\u00eas, doar at\u00e9 10% dos animais abrigados.  Art. 3\u00ba. A Associa\u00e7\u00e3o dever\u00e1 prestar contas ao Munic\u00edpio, comprovando as despesas realizadas com o recurso recebido.  Art. 4\u00ba. Esta lei entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.        PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos doze dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI N\u00ba 791\/2022 - DE 12 DE DEZEMBRO DE 2022  \u201cDISP\u00d5E SOBRE O ATENDIMENTO PREFERENCIAL AOS PORTADORES DE FIBROMIALGIA NOS LOCAIS QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d  FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVOU e eu, Prefeita Municipal, SANCIONO a seguinte Lei:  Art. 1\u00ba - Ficam os \u00f3rg\u00e3os p\u00fablicos, empresas p\u00fablicas, empresas concession\u00e1rias de servi\u00e7os p\u00fablicos e empresas privadas localizadas no Munic\u00edpio de Guara\u00ed-TO, obrigados a conceder atendimento preferencial \u00e0s pessoas portadoras de fibromialgia.  Art. 2\u00ba - As empresas comerciais que recebem pagamentos de contas dever\u00e3o incluir as pessoas portadoras de fibromialgia nas filas de atendimento preferencial aos idosos, gestantes e pessoas com defici\u00eancia.  Art. 3\u00ba - O atendimento preferencial previsto nesta lei ter\u00e1 o mesmo tratamento daquele concedido \u00e0s pessoas com defici\u00eancia, os idosos com idade igual ou superior a 60 (sessenta) anos, as gestantes, as lactantes, as pessoas com crian\u00e7as de colo e os obesos, nos termos da Lei Federal n.\u00ba 10.048, de 08 de novembro de 2000.  Art. 4\u00ba - A identifica\u00e7\u00e3o dos portadores de fibromialgia se dar\u00e1 mediante apresenta\u00e7\u00e3o de cart\u00e3o de prioridade, que \u00e9 concedido pela Secret\u00e1ria Municipal de Sa\u00fade. Caso n\u00e3o possua este cart\u00e3o \u00e9 aceit\u00e1vel a apresenta\u00e7\u00e3o de laudo ou atestado m\u00e9dico que comprove a condi\u00e7\u00e3o do portador da referida enfermidade.  Art. 5\u00ba - O Chefe do Poder Executivo Municipal regulamentar\u00e1 a presente lei, no prazo de 60 (sessenta) dias contados de sua publica\u00e7\u00e3o.  Art. 6\u00ba - Esta lei entra em vigor na data da sua publica\u00e7\u00e3o.   PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos doze dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI COMPLEMENTAR N\u00ba 088\/2022 - DE 12 DE DEZEMBRO DE 2022.   \u201cAUTORIZA DOA\u00c7\u00c3O E ESCRITURA\u00c7\u00c3O DEFINITIVA DE TERRENO NO SETOR AEROPORTO, EM FAVOR DE LEOPOLDO ALVES DA SILVA, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS.\u201d    FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVOU, e eu, Prefeita Municipal, no uso de minhas atribui\u00e7\u00f5es legais, SANCIONO a seguinte Lei:  Art. 1\u00ba Fica o Chefe do Poder Executivo autorizado a doar um lote de terreno nesta cidade de Guara\u00ed\/TO, situado na Av. B-04, constitu\u00eddo pela integridade do Lote n\u00ba 19, da Quadra 24, do Setor Aeroporto, com os seguintes limites e confronta\u00e7\u00f5es:   inicia-se a descri\u00e7\u00e3o deste per\u00edmetro no v\u00e9rtice M 001, de coordenadas  48\u00b029\u201951,027\u201d W e  8\u00b051\u203a15,477\u00bb S; deste segue confrontando com a propriedade de AV. FORTALEZA, com azimute de 127\u00b052\u201937\u201d por uma dist\u00e2ncia de 36,46m  at\u00e9 o v\u00e9rtice M 002, de coordenadas  48\u00b029\u201950,081\u201d W e  8\u00b051\u203a16,199\u00bb S; deste segue confrontando com a propriedade de com azimute de 252\u00b019\u201952\u201d por uma dist\u00e2ncia de 20,37m  at\u00e9 o v\u00e9rtice M 002, de coordenadas  48\u00b029\u201950,714\u201d W e  8\u00b051\u203a16,404\u00bb S; deste segue confrontando com a propriedade de RUA BARNAB\u00c9, com azimute 341\u00b050\u201909\u201d por uma dist\u00e2ncia de 30,07m  at\u00e9 o v\u00e9rtice M 001, ponto inicial da descri\u00e7\u00e3o deste per\u00edmetro,  para o Sr. Leopoldo Alves da Silva, brasileiro, portador da CI\/RG n\u00ba 1.105.499-SSP\/TO, e do CPF n\u00ba 168.544.001-49.    \u00a71\u00ba - Fica proibida a venda do im\u00f3vel doado neste artigo, pelo per\u00edodo de 10 (dez) anos, sob pena do mesmo retornar ao Patrim\u00f4nio Municipal de Guara\u00ed. \u00a72\u00b0 - Fica determinado \u00e0 obrigatoriedade de realizar benfeitoria no presente im\u00f3vel, por parte do benefici\u00e1rio, no prazo de 36 (trinta e seis) meses, sob pena do mesmo retornar ao Patrim\u00f4nio Municipal de Guara\u00ed. \u00a7 3\u00b0 A presente doa\u00e7\u00e3o s\u00f3 ser\u00e1 efetivada mediante a apresenta\u00e7\u00e3o, por parte do benefici\u00e1rio, das Certid\u00f5es Negativas de Im\u00f3veis.  Art. 2\u00ba Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o, ficando revogado demais disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos doze dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI COMPLEMENTAR N\u00ba089 DE 12 DE DEZEMBRO DE 2022.  DISP\u00d5E SOBRE ALTERA\u00c7\u00c3O A LEI MUNICIPAL N\u00ba 638\/2016, DEFININDO NOVO PLANO DE AMORTIZA\u00c7\u00c3O DO D\u00c9FICIT ATUARIAL DO RPPS DO MUNIC\u00cdPIO DE GUARA\u00cd\/TO E D\u00c1 OUTRAS PROVID\u00caNCIAS.  FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVOU, e eu, Prefeita Municipal, no uso de minhas atribui\u00e7\u00f5es legais, SANCIONO a seguinte Lei:  Art. 1\u00ba. O inciso IV do artigo 48 da Lei Municipal n\u00ba 638\/2016 passa a vigorar com a seguinte reda\u00e7\u00e3o: Art. 48. ..................................................................................................... IV - de uma contribui\u00e7\u00e3o mensal do Munic\u00edpio, inclu\u00eddas suas autarquias e funda\u00e7\u00f5es, relativa ao custo normal, definida na reavalia\u00e7\u00e3o atuarial, igual a 17,25% (dezessete inteiros e vinte e cinco cent\u00e9simos percentuais), calculada sobre a remunera\u00e7\u00e3o de contribui\u00e7\u00e3o dos segurados ativos, j\u00e1 inclu\u00edda a taxa de administra\u00e7\u00e3o necess\u00e1ria \u00e0 organiza\u00e7\u00e3o e funcionamento da unidade gestora;  Art. 2\u00ba. Fica institu\u00eddo plano de amortiza\u00e7\u00e3o destinado ao equacionamento do d\u00e9ficit atuarial apurado em 2022, incidente sobre a totalidade da remunera\u00e7\u00e3o de contribui\u00e7\u00e3o dos segurados ativos, conforme al\u00edquotas de contribui\u00e7\u00e3o suplementar devidas pelo Ente, iniciando com 11,52% (onze inteiros e cinquenta e dois cent\u00e9simos percentuais) e escalonadas conforme tabela abaixo.  Ano\tCusto Suplementar 2022\t11,52% 2023\t20,01% 2024\t29,89% 2025\t30,12% 2026\t30,35% 2027\t30,59% 2028\t30,83% 2029\t31,07% 2030\t31,31% 2031\t31,55% 2032\t31,80% 2033\t32,05% 2034\t32,29% 2035\t32,55% 2036\t32,80% 2037\t33,05% 2038\t33,31% 2039\t33,57% 2040\t33,83% 2041\t34,10% 2042\t34,36% 2043\t34,63% 2044\t34,90% 2045\t35,17% 2046\t35,44% 2047\t35,72% 2048\t36,00% 2049\t36,28% 2050\t36,56% 2051\t36,84% 2052\t37,13% 2053\t37,42% 2054\t37,71% 2055\t38,00% 2056\t38,30%   Art. 3\u00ba. A cobran\u00e7a das contribui\u00e7\u00f5es previdenci\u00e1rias previstas nos artigos 1\u00ba e 2\u00ba somente poder\u00e1 ser exigida a partir do primeiro dia do m\u00eas subsequente depois de decorridos 90 (noventa) dias da data de publica\u00e7\u00e3o desta Lei, conforme preceitua o \u00a7 6\u00ba do artigo 195 da Constitui\u00e7\u00e3o Federal.  Art. 4\u00ba. Esta Lei entrar\u00e1 em vigor na data de sua publica\u00e7\u00e3o para fins de homologa\u00e7\u00e3o do resultado da reavalia\u00e7\u00e3o atuarial de 2022, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  \t PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos 12 (doze) dias do m\u00eas de dezembro do ano de 2022 (dois mil e vinte e dois).  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI COMPLEMENTAR N\u00b0 090\/2022 DE 12 DE DEZEMBRO DE 2022   \u201cALTERA A LEI COMPLEMENTAR N\u00ba. 008, DE 22 DE DEZEMBRO DE 2017, E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d   A PREFEITA MUNICIPAL DE GUARA\u00cd -TO, no uso da atribui\u00e7\u00e3o que lhe confere o art. 56 da Lei Org\u00e2nica Municipal, adota a seguinte Medida Provis\u00f3ria, com for\u00e7a de lei:  Art. 1\u00ba. Ficam extintos da estrutura organizacional institu\u00edda pela Lei Complementar n\u00ba 008, de 22 de dezembro de 2017, alterada pela Lei Complementar n\u00ba 044, de 22 de novembro de 2019, Lei Complementar n\u00ba 058, de 28 de abril de 2021, pela Lei Complementar n\u00ba 059, de 13 de maio de 2021 e pela Lei Complementar 083 de 13 de outubro de 2022 os cargos abaixo nominados, cuja aloca\u00e7\u00e3o funcional segue detalhada:  SECRETARIA MUNICIPAL DE ARTICULA\u00c7\u00c3O INSTITUCIONAL E DESENVOLVIMENTO  N\u00cdVEL\tLOTA\u00c7\u00c3O\/ DENOMINA\u00c7\u00c3O\tSAL\u00c1RIO\/BASE-R$\tQUANT. DAI-I\tGerente de Articula\u00e7\u00e3o\tR$ 2.500,00\t01 DAI-I\tGerente de Recursos Humanos\tR$ 2.500,00\t01   Art. 2\u00ba. Ficam criados, na estrutura organizacional institu\u00edda pela Lei Complementar n\u00ba. 008, de 22 de dezembro de 2017, os cargos abaixo nominados, cuja aloca\u00e7\u00e3o funcional segue detalhada:  SECRETARIA MUNICIPAL DE ARTICULA\u00c7\u00c3O INSTITUCIONAL E DESENVOLVIMENTO  N\u00cdVEL\tLOTA\u00c7\u00c3O\/ DENOMINA\u00c7\u00c3O\tSAL\u00c1RIO\/BASE-R$\tQUANT DAS-IV\tDiretor de Articula\u00e7\u00e3o\tR$ 3.000,00\t01 SECRETARIA MUNICIPAL DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O N\u00cdVEL\tLOTA\u00c7\u00c3O\/ DENOMINA\u00c7\u00c3O\tSAL\u00c1RIO\/BASE-R$\tQUANT. DAS-III\tSuperintendente de Recursos Humanos \tR$ 4.000,00\t01   Par\u00e1grafo \u00fanico. As atribui\u00e7\u00f5es dos cargos criados neste artigo ser\u00e3o as definidas abaixo, passando a ser parte integrante do Anexo II da Lei Complementar n\u00ba. 008, de 22 de dezembro de 2017, de modo que compete ao:  I - Diretor de Articula\u00e7\u00e3o:  I-Conduzir as fases de articula\u00e7\u00e3o do governo Municipal com os \u00f3rg\u00e3os governamentais,  II-elaborar e acompanhar as audi\u00eancias p\u00fablicas marcadas, a execu\u00e7\u00e3o de conv\u00eanios, a tramita\u00e7\u00e3o processual e a presta\u00e7\u00e3o de contas, promover as articula\u00e7\u00f5es administrativas e rela\u00e7\u00f5es intersetoriais que sejam necess\u00e1rias \u00e0 integra\u00e7\u00e3o das diversas \u00e1reas de funcionamento da Prefeitura Municipal;  III- promo\u00e7\u00e3o das rela\u00e7\u00f5es institucionais com o legislativo municipal, com os demais munic\u00edpios e com as comunidades organizadas.  II - Superintendente de Recursos Humanos:  I - controlar a folha de pagamento; a) - administrar o cadastro central de recurso humanos e o controle da folha de pagamento, para invent\u00e1rio e diagn\u00f3stico permanentes da for\u00e7a de trabalho dispon\u00edvel da Administra\u00e7\u00e3o P\u00fablica Municipal, de modo a permitir o recrutamento interno, a programa\u00e7\u00e3o de concursos p\u00fablicos, a concess\u00e3o de direitos e vantagens, a an\u00e1lise de custos para concess\u00e3o de aumentos peri\u00f3dicos de vencimentos e pagamentos de sal\u00e1rios aos servidores municipais; II - coordenar a avalia\u00e7\u00e3o de desempenho, para fins de promo\u00e7\u00e3o, treinamento, remo\u00e7\u00e3o, readapta\u00e7\u00e3o e dispensa; III - recrutar e selecionar pessoal; a) - proceder \u00e0 administra\u00e7\u00e3o de pessoal, relativas admiss\u00e3o, lota\u00e7\u00e3o, movimenta\u00e7\u00e3o e demiss\u00e3o de servidores de qualquer regime jur\u00eddico para a Administra\u00e7\u00e3o Municipal; IV - recadastrar o quadro de pessoal; V - implantar o Plano de Carreira; a) - promover a administra\u00e7\u00e3o e o controle do quadros, cargos, fun\u00e7\u00f5es e vencimentos dos \u00f3rg\u00e3os da Administra\u00e7\u00e3o Direta, coo objetivo de assegurar a execu\u00e7\u00e3o de uma pol\u00edtica de pessoal condizente com Plano de Carreira e Vencimentos; b) - formular e executar a pol\u00edtica de recurso humanos e a sua integra\u00e7\u00e3o com a estrutura administrativa municipal; VI \u2013 auxiliar na realiza\u00e7\u00e3o de concursos p\u00fablicos; VII - consolidar os direitos e deveres dos servidores p\u00fablicos municipais; VIII - capacitar, desenvolver e valorizar do servido p\u00fablico; a) - levantar as necessidades de treinamento em cada \u00f3rg\u00e3o da Administra\u00e7\u00e3o Direta, consultando os respectivos chefes, com vistas \u00e0 consecu\u00e7\u00e3o do melhor rendimento da m\u00e3o-de-obra dispon\u00edvel questionando os servidores para verificar suas car\u00eancias em termos de cultura profissional, bem como entrevistando a clientela, no sentido de obter informa\u00e7\u00f5es necess\u00e1rias a desenvolvimento de programas de forma\u00e7\u00e3o e de capacita\u00e7\u00e3o de pessoal, para subsidiar o treinamento na concep\u00e7\u00e3o da pol\u00edtica e desenvolvimento de recurso humanos da Prefeitura; IX - prepara as informa\u00e7\u00f5es e manter controle do mecanismos necess\u00e1rios \u00e0 aplica\u00e7\u00e3o das disposi\u00e7\u00f5es dos Estatutos dos Servidores do Munic\u00edpio; X - elaborar Registros de Acompanhamento Individual, que servir\u00e1 de base para atendimento a quaisquer vantagens a que fa\u00e7a jus servidor; XI - manter controle di\u00e1rio da frequ\u00eancia dos servidores; XII - manter controle da documenta\u00e7\u00e3o de pessoal, com forma\u00e7\u00e3o de \u201cdossi\u00ea\u201d, XIII - propor treinamento, cursos, palestras encontros, visando o aperfei\u00e7oamento do servidor; XIV - gerir os recursos, programas e a\u00e7\u00f5es de previd\u00eancia e assist\u00eancia social; XV - exercer outras atividades compat\u00edveis com natureza de suas fun\u00e7\u00f5es e que lhe forem atribu\u00eddas pela secretaria da administra\u00e7\u00e3o  Art. 3\u00ba.  Fica acrescido as seguintes fun\u00e7\u00f5es no \u00a74\u00b0 do art. 20 da Lei Complementar n\u00ba. 008, de 22 de dezembro de 2017:  \u201cArt. 20................................ .(...)  \u00a74\u00b0. Ao Respons\u00e1vel T\u00e9cnico pela Farm\u00e1cia B\u00e1sica, Laborat\u00f3rio Municipal, Postos de Coletas Laboratorial, Centro de Controle de Zoonoses \u2013 CC, Odontologia e Educador F\u00edsico, ser\u00e3o concedidos uma gratifica\u00e7\u00e3o de 20% (vinte por cento) sobre o sal\u00e1rio base. \u201d (NR)  Art. 4\u00b0. Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o, surtindo efeitos a partir de 1\u00ba de julho de 2022.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos doze dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  LEI COMPLEMENTAR N\u00ba. 091\/2022-DE 12 DE DEZEMBRO DE 2022.  \u201cESTIMA A RECEITA E FIXA A DESPESA DO OR\u00c7AMENTO ANUAL DO MUNIC\u00cdPIO DE GUARA\u00cd PARA O EXERC\u00cdCIO FINANCEIRO DE 2022, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d   A PrefeitA Municipal de guara\u00ed, Estado do Tocantins, faz saber que a C\u00e2mara Municipal, no uso de suas atribui\u00e7\u00f5es legais e constitucionais, aprovou e eu sanciono a seguinte lei:  TITULO I DO CONTE\u00daDO DA LEI OR\u00c7AMENT\u00c1RIA  Art. 1\u00ba. Esta Lei estima a receita e fixa a despesa do Or\u00e7amento Anual do Munic\u00edpio de GUARA\u00cd, para o exerc\u00edcio financeiro de 2022, nos termos das disposi\u00e7\u00f5es constitucionais, compreendendo:   I \u2013 O Or\u00e7amento Fiscal referente aos Poderes Legislativo e Executivo, seus \u00f3rg\u00e3os, entidades e fundos da administra\u00e7\u00e3o direta e indireta.   II \u2013 O Or\u00e7amento de Seguridade Social, abrangendo todas as entidades e \u00f3rg\u00e3os a ela vinculados, bem como os fundos institu\u00eddos e mantidos pelo Poder P\u00fablico.  TITULO II DOS OR\u00c7AMENTOS FISCAL E DA SEGURIDADE SOCIAL  CAP\u00cdTULO I DA ESTIMATIVA DA RECEITA  Art. 2\u00ba. A Receita total estimada nos Or\u00e7amentos Fiscal e da Seguridade Social \u00e9 no valor de R$ 92.000.000,00 (noventa e dois milh\u00f5es de reais).   Art. 3\u00ba. A Receita decorrer\u00e1 da arrecada\u00e7\u00e3o de tributos, contribui\u00e7\u00f5es e outras receitas correntes e de capital, previstas na legisla\u00e7\u00e3o vigente e estimadas com o seguinte desdobramento:  OR\u00c7AMENTO \u2013 2022  T\u00cdTULOS\tTOTAL (R$) RECEITA TRIBUT\u00c1RIA\t10.872209,24 RECEITA DE CONTRIBUI\u00c7\u00d5ES\t2.387.140,00 RECEITA PATRIMONIAL\t969.736,00 RECEITA SERVI\u00c7OS\t19.700,00 TRANSFER\u00caNCIAS CORRENTES\t64.310.961,71 RECEITAS CORRENTES INTRA-OR\u00c7AMENT\u00c1RIAS\t1.522.860,00 OUTRAS RECEITAS CORRENTES\t17.000,00 SUB-TOTAL\t80.099.606,95 TRANFER\u00caNCIAS DE CAPITAL\t11.900.393,05 SUB-TOTAL\t11.900.393,05 TOTAL GERAL\t92.000.000,00   Art. 4\u00ba. A Receita ser\u00e1 realizada com base na arrecada\u00e7\u00e3o direta das transfer\u00eancias constitucionais, das transfer\u00eancias volunt\u00e1rias e de outras rendas na forma da legisla\u00e7\u00e3o em vigor, de acordo com os c\u00f3digos, denomina\u00e7\u00f5es e detalhamentos da Receita P\u00fablica, institu\u00eddos pelas Portarias do Secret\u00e1rio do Tesouro Nacional do Minist\u00e9rio da Fazenda, que aprova o Manual de Procedimentos da Receita P\u00fablica.   CAP\u00cdTULO II DA FIXA\u00c7\u00c3O DA DESPESA  Art. 5\u00ba. A Despesa total fixada \u00e9 no valor de R$ 92.000.000,00 (noventa e dois milh\u00f5es de reais).  I \u2013 Or\u00e7amento fiscal em R$29.299.353,04 (vinte e nove milh\u00f5es, duzentos e novente e nove mil, trezentos e cinquenta e tr\u00eas reais e quatro centavos).  II \u2013 Or\u00e7amento da seguridade social em R$ 3.010.000,00 (tr\u00eas milh\u00f5es e dez mil reais).   Art. 6\u00ba. A Despesa fixada \u00e0 conta dos recursos previstos neste cap\u00edtulo, observado a programa\u00e7\u00e3o anexa a esta Lei, apresenta o seguinte desdobramento:  I \u2013 Por \u00d3rg\u00e3os: DISCRIMINA\u00c7\u00c3O\tFISCAL\tSEGURIDADE\tTOTAL AGENCIA MUL REGULA\u00c7\u00c3O DOS SERV AGUA ESGOTOS-AMAE\t150.000,00\t\u00a0\t150.000,00 CAMARA MUNICIPAL\t3.590.000,00\t\u00a0\t3.590.000,00 FUNDEG\t104.500,00\t\u00a0\t104.500,00 FUNDESPORTES\t265.552,00\t\u00a0\t265.552,00 FUNDO MUL DA CRIAN\u00c7A E DO ADOLESCENTE\t46.932,44\t\u00a0\t46.932,44 FUNDO MUL DOS DIREITOS DO IDOSO\t193.199,60\t\u00a0\t193.199,60 FUNDO MUNICIPAL DE ASSISTENCIA SOCIAL\t4.099.169,00\t\u00a0\t4.099.169,00 FUNDO MUNICIPAL DE EDUCA\u00c7\u00c3O\t22.860.169,79\t\u00a0\t22.860.169,79 FUNDO MUNICIPAL DE SAUDE DE GUARAI\t21.000.000,00\t\u00a0\t21.000.000,00 GABINETE DO PREFEITO\t858.930,00\t\u00a0\t858.930,00 GUARAIPREV\t\u00a0\t3.010.000,00\t3.010.000,00 SECRET DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O\t9.027.440,17\t\u00a0\t9.027.440,17 SECRETARIA DE  JUVENTUDE, ESPORTE E TURISMO\t1.397.081,00\t\u00a0\t1.397.081,00 SECRETARIA DE EDUCA\u00c7AO E CULTURA\t523.206,00\t\u00a0\t523.206,00 SECRETARIA MUL DE AGRICULTURA, MEIO AMBIENTE E REC HIDRICOS\t11.102.700,00\t\u00a0\t11.102.700,00 SECRETARIA MUL DE INFRA-ESTRUTURA  E OBRAS\t11.467.534,00\t\u00a0\t11.467.534,00 SECRETARIA MUL DE ART. INST. E DESENVOLVIMENTO.\t2.303.586,00\t\t2.303.586,00 TOTAL GERAL\t88.990.000,00\t3.010.000,00\t92.000.000,00   II \u2013 Por Fun\u00e7\u00f5es:  DISCRIMINA\u00c7\u00c3O\tFISCAL\tSEGURIDADE\tTOTAL ADMINISTRA\u00c7\u00c3O\t11.674.184,17\t\t11.674.184,17 AGRICULTURA\t430.000,00\t\t430.000,00 ASSIST\u00caNCIA SOCIAL\t193.199,60\t\t193.199,60 ASSIST\u00caNCIA SOCIAL\t4.099.169,00\t\t4.099.169,00 ASSIST\u00caNCIA SOCIAL\t46.932,44\t\t46.932,44 COMUNICA\u00c7\u00d5ES\t63.370,00\t\t63.370,00 COM\u00c9RCIO E SERVI\u00c7OS\t1.745.486,00\t\t1.745.486,00 CULTURA\t523.206,00\t\t523.206,00 DESPORTO E LAZER\t265.552,00\t\t265.552,00 DESPORTO E LAZER\t470.360,00\t\t470.360,00 EDUCA\u00c7\u00c3O\t104.500,00\t\t104.500,00 EDUCA\u00c7\u00c3O\t22.860.169,79\t\t22.860.169,79 ENCARGOS ESPECIAIS\t1.130.000,00\t\t1.130.000,00 ENERGIA\t1.425.000,00\t\t1.425.000,00 GEST\u00c3O AMBIENTAL\t6.283.700,00\t\t6.283.700,00 HABITA\u00c7\u00c3O\t1.525.070,00\t\t1.525.070,00 IND\u00daSTRIA\t1.542.000,00\t\t1.542.000,00 JUDICI\u00c1RIA\t50.000,00\t\t50.000,00 LEGISLATIVA\t3.590.000,00\t\t3.590.000,00 PREVID\u00caNCIA SOCIAL\t\t3.010.000,00\t3.010.000,00 SANEAMENTO\t2.595.400,00\t\t2.595.400,00 SA\u00daDE\t21.000.000,00\t\t21.000.000,00 SEGURAN\u00c7A P\u00daBLICA\t14.000,00\t\t14.000,00 TRABALHO\t113.567,00\t\t113.567,00 TRANSPORTE\t3.446.000,00\t\t3.446.000,00 URBANISMO\t3.799.134,00\t\t3.799.134,00 TOTAL GERAL\t88.990.000,00\t3.010.000,00\t92.000.000,00   III \u2013 Por Unidades Administrativas:   DISCRIMINA\u00c7\u00c3O\tTOTAL AGENCIA MUL REGULA\u00c7\u00c3O DOS SERV AGUA ESGOTOS-AMAE\t150.000,00 CAMARA MUNICIPAL\t3.590.000,00 FUNDEG\t104.500,00 FUNDESPORTES\t262.552,00 FUNDO MUL DA CRIAN\u00c7A E DO ADOLESCENTE\t46.932,44 FUNDO MUL DOS DIREITOS DO IDOSO\t193.199,60 FUNDO MUNICIPAL DE ASSISTENCIA SOCIAL\t4.099.169,00 FUNDO MUNICIPAL DE EDUCA\u00c7\u00c3O\t22.860.169,79 FUNDO MUNICIPAL DE SAUDE DE GUARAI\t21.000.000,00 GABINETE DO PREFEITO\t858.930,00 GUARAIPREV\t3.010.000,00 SECRET DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O\t9.027.440,17 SECRETARIA DE  JUVENTUDE, ESPORTE E TURISMO\t1.397.081,00 SECRETARIA DE EDUCA\u00c7AO E CULTURA\t523.206,00 SECRETARIA MUL DE AGRICULTURA, MEIO AMBIENTE E REC HIDRICOS\t11.102.700,00 SECRETARIA MUL DE INFRA-ESTRUTURA  E OBRAS\t11.467.534,00 SECRETARIA MUL DE ART. INST. E DESENVOLVIMENTO\t2.303.586,00 TOTAL GERAL\t92.000.000,00  CAP\u00cdTULO III DAS AUTORIZA\u00c7\u00d5ES  \tArt. 7\u00ba. Fica o Chefe do Poder Executivo autorizado a:  \tI \u2013 Abrir cr\u00e9ditos suplementares nos limites e com os recursos abaixo indicados:  a) Decorrentes de super\u00e1vit financeiro at\u00e9 o limite de 100% (cem por cento) do mesmo, de acordo com o estabelecido no art. 43, \u00a7 1\u00ba, Inciso I e \u00a7 2\u00ba, da Lei 4.320\/64;  b)Decorrentes do excesso de arrecada\u00e7\u00e3o at\u00e9 o limite de 100% (cem por cento) do mesmo, conforme o estabelecido no art. 43, \u00a7 1\u00ba, Inciso II e \u00a7\u00a7 3\u00ba e 4\u00ba, da Lei 4.320\/64; c)Decorrentes de anula\u00e7\u00e3o parcial ou total de dota\u00e7\u00f5es na forma definida na Lei de Diretrizes Or\u00e7ament\u00e1rias do exerc\u00edcio de 2022, at\u00e9 o limite de 50% (cinquenta por cento) das mesmas, conforme o estabelecido no art. 43, \u00a7 1\u00ba, Inciso III, da Lei 4.320\/64, e com base no Art. 167, Inciso VI, da Constitui\u00e7\u00e3o Federal. Tamb\u00e9m fica o Poder Executivo autorizado, atrav\u00e9s de Decreto, abrir cr\u00e9dito especial adicional por anula\u00e7\u00e3o total ou parcial de dota\u00e7\u00e3o, at\u00e9 10% (dez por cento) do or\u00e7amento vigente para cobrir eventuais novos programas que possam surgir no decorrer do exerc\u00edcio de 2022.  d)Decorrentes de altera\u00e7\u00e3o de QDD, permitindo inclusive \u00e0 cria\u00e7\u00e3o de elementos e sub-elementos necess\u00e1rios \u00e0 execu\u00e7\u00e3o da despesa desde que atenda a categoria econ\u00f4mica a ser reduzida.  II - Efetuar opera\u00e7\u00f5es de cr\u00e9ditos por antecipa\u00e7\u00e3o da receita, nos limites fixados pelo Senado Federal e na forma do disposto no art. 38, da Lei complementar n\u00ba 101\/2000- Lei de Responsabilidade Fiscal.  Art. 8\u00ba. Fica o Poder Executivo Municipal autorizado a abrir Cr\u00e9dito Especial Extraordin\u00e1rio na forma desta Lei, mediante Decreto com as devidas justificativas.  Art. 9\u00ba. Fica o Poder Executivo autorizado a estabelecer normas complementares pertinentes a execu\u00e7\u00e3o do or\u00e7amento e, no que couber adequ\u00e1-la as disposi\u00e7\u00f5es da Constitui\u00e7\u00e3o do Munic\u00edpio de Guara\u00ed, compreendendo tamb\u00e9m a programa\u00e7\u00e3o financeira para o exerc\u00edcio de 2022.  Art. 10. O Poder Executivo poder\u00e1, mediante Decreto, transpor, remanejar, transferir ou utilizar, total ou parcialmente, as dota\u00e7\u00f5es or\u00e7ament\u00e1rias aprovadas nesta Lei e em seus cr\u00e9ditos adicionais em decorr\u00eancia da extin\u00e7\u00e3o, transforma\u00e7\u00e3o, transfer\u00eancia, incorpora\u00e7\u00e3o ou desmembramento de \u00f3rg\u00e3os e entidades, bem como altera\u00e7\u00f5es de suas compet\u00eancias ou atribui\u00e7\u00f5es, mantida a estrutura program\u00e1tica, expressa por categoria de programa\u00e7\u00e3o.   Art. 11. Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o, surtindo seus efeitos retroativos a 1\u00ba (primeiro) de janeiro de 2022, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, aos doze dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal   LEI COMPLEMENTAR N\u00ba 092\/2022 DE 12 DE DEZEMBRO DE 2022.  \u201cDISP\u00d5E SOBRE AS DIRETRIZES OR\u00c7AMENT\u00c1RIAS PARA O EXERC\u00cdCIO DE 2022, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS\u201d.  FA\u00c7O SABER que a C\u00e2mara Municipal de Guara\u00ed, Estado do Tocantins, APROVA e eu Prefeita Municipal, no uso de minhas atribui\u00e7\u00f5es legais, SANCIONO a seguinte Lei: CAP\u00cdTULO I Das Diretrizes Gerais  Art. 1\u00ba. Ficam estabelecidas as diretrizes para a elabora\u00e7\u00e3o dos Or\u00e7amentos do Munic\u00edpio de Guara\u00ed, relativos ao exerc\u00edcio de 2022, as diretrizes gerais de que trata este Cap\u00edtulo, os princ\u00edpios estabelecidos na Constitui\u00e7\u00e3o Federal, art. 165, na Lei Org\u00e2nica do Munic\u00edpio, na Lei Federal n\u00ba. 4.320\/64 de 17 de mar\u00e7o de 1964 e na Lei de Responsabilidade Fiscal, Lei Complementar Federal n\u00ba. 101\/2000.  Art. 2\u00ba. As diretrizes fixadas por esta Lei tem a finalidade prec\u00edpua de permitir que a administra\u00e7\u00e3o p\u00fablica municipal possa continuar suas a\u00e7\u00f5es visando promover o equil\u00edbrio das finan\u00e7as p\u00fablicas, ao mesmo tempo possibilitando a forma\u00e7\u00e3o de poupan\u00e7a interna para aplica\u00e7\u00e3o em investimentos, programas sociais e demais a\u00e7\u00f5es.  Par\u00e1grafo \u00danico \u2013 O equil\u00edbrio das finan\u00e7as e a forma\u00e7\u00e3o de poupan\u00e7a interna dever\u00e3o ser alcan\u00e7ados atrav\u00e9s de ajuste fiscal, destacando-se neste, as seguintes medidas:  I \u2013 incremento da Arrecada\u00e7\u00e3o: a) aumento real da arrecada\u00e7\u00e3o tribut\u00e1ria; inscri\u00e7\u00e3o e recebimento da d\u00edvida ativa tribut\u00e1ria.  II \u2013 controle de Despesa: redu\u00e7\u00e3o de despesa com custeio administrativo e operacional; r\u00edgido controle das despesas com pessoal e encargos sociais; emplementa\u00e7\u00e3o, em especial, ao combate a pandemia \u2013 Covid19 Execu\u00e7\u00e3o de investimentos dentro da capacidade de desembolso do munic\u00edpio.  Art. 3\u00ba.  A Lei Or\u00e7ament\u00e1ria Anual compreender\u00e1:  I \u2013 Or\u00e7amento Fiscal; e  II \u2013 Or\u00e7amento da Seguridade Social.  Art. 4\u00ba. Na estimativa das receitas ser\u00e3o considerados os efeitos das modifica\u00e7\u00f5es na legisla\u00e7\u00e3o tribut\u00e1ria, que ser\u00e3o objeto de projetos de lei a serem encaminhados \u00e0 C\u00e2mara Municipal antes do encerramento do atual exerc\u00edcio financeiro.  Art. 5\u00ba. As atividades e projetos para efeito desta Lei ser\u00e3o assim definidos:  Par\u00e1grafo \u00danico \u2013 Cada atividade e projeto identificar\u00e1 a fun\u00e7\u00e3o e a sub fun\u00e7\u00e3o \u00e0s quais se vinculam:  I \u2013 ATIVIDADES OPERACIONAIS \u2013 S\u00e3o aquelas destinadas ao apoio da organiza\u00e7\u00e3o, ou seja, as que obrigam as atividades de or\u00e7amento, contabilidade, administra\u00e7\u00e3o de pessoal, almoxarifado, planejamento e outras afins, bem assim as demais relacionadas com a execu\u00e7\u00e3o das atividades fim do setor p\u00fablico;  II \u2013 PROJETO DE APERFEI\u00c7OAMENTO \u2013 S\u00e3o os que objetivam melhorar a produ\u00e7\u00e3o de bens e a presta\u00e7\u00e3o de servi\u00e7os atrav\u00e9s do desenvolvimento de projetos destinados basicamente \u00e0 moderniza\u00e7\u00e3o administrativa, tecnol\u00f3gica e gerencial do setor p\u00fablico;  III \u2013 PROJETO DE AMPLIA\u00c7\u00c3O, REFORMA E CONSTRU\u00c7\u00c3O \u2013 S\u00e3o os que visam incrementar a capacidade instalada pelo Poder P\u00fablico, seja ela relacionada com os bens do pr\u00f3prio Setor P\u00fablico ou com os de uso comum da comunidade em geral, ou ainda, com os de setores produtivos;  IV \u2013 PROJETO DE DESAPROPRIA\u00c7\u00c3O - S\u00e3o aqueles que sejam necess\u00e1rios \u00e0 Administra\u00e7\u00e3o realizar em prol de melhorias, expans\u00e3o urbana e preserva\u00e7\u00e3o hist\u00f3rica que sejam da compet\u00eancia do Munic\u00edpio e do Plano Diretor;  V \u2013 PROJETOS DE EXPANS\u00c3O DOS SERVI\u00c7OS \u2013 S\u00e3o os que visam expandir a capacidade de presta\u00e7\u00e3o de servi\u00e7os sem que isto implique na execu\u00e7\u00e3o de obras e sim na manuten\u00e7\u00e3o de infraestrutura b\u00e1sica.  Art. 6\u00ba.  As categorias de programa\u00e7\u00e3o de que trata esta Lei ser\u00e3o identificadas no Projeto de Lei Or\u00e7ament\u00e1ria por Fun\u00e7\u00e3o, Sub fun\u00e7\u00e3o, Programas, Atividades e Projetos. CAP\u00cdTULO II Do Or\u00e7amento Fiscal  Art. 7\u00ba. O Or\u00e7amento Fiscal abranger\u00e1 os Poderes do Munic\u00edpio, seus fundos, \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o direta e indireta.  Art. 8\u00ba. Na elabora\u00e7\u00e3o do Or\u00e7amento Fiscal ser\u00e3o observadas as diretrizes espec\u00edficas de que trata este Cap\u00edtulo.  Art. 9\u00ba. Na fixa\u00e7\u00e3o das despesas ser\u00e3o observadas as metas fiscais constantes dos anexos desta Lei. Paragrafo \u00fanico \u2013 As metas fiscais ser\u00e3o atualizadas no momento do envio do Projeto da Lei Or\u00e7ament\u00e1ria, devido a incerteza quanto as proje\u00e7\u00f5es fiscais para os exercicios; 2022, 2023 e 2024 por motivo da Pandemia internacional \u2013 Covid-19.  Art. 10. A proposta or\u00e7ament\u00e1ria alocar\u00e1 recursos espec\u00edficos para os Poderes: Executivo, Legislativo e para os seus \u00f3rg\u00e3os, nos termos da Lei Org\u00e2nica Municipal.  CAP\u00cdTULO III Do Or\u00e7amento da Seguridade Social  Art. 11. O Or\u00e7amento da Seguridade Social abranger\u00e1 os \u00f3rg\u00e3os e unidades or\u00e7ament\u00e1rias, inclusive fundos, funda\u00e7\u00f5es, autarquias e empresas p\u00fablicas que atuem nas \u00e1reas de sa\u00fade, previd\u00eancia e assist\u00eancia social.  Art. 12. Na elabora\u00e7\u00e3o do Or\u00e7amento da Seguridade Social ser\u00e3o observadas as diretrizes espec\u00edficas de que trata esta Lei.  Art. 13. Os \u00f3rg\u00e3os e as unidades or\u00e7ament\u00e1rias com atribui\u00e7\u00f5es relativas a sa\u00fade, inclusive saneamento b\u00e1sico, previdenci\u00e1ria e assist\u00eancia social, dever\u00e3o compor o Or\u00e7amento da Seguridade Social, no qual suas despesas para prioridades e metas constam do Anexo desta Lei.  CAP\u00cdTULO IV Das Disposi\u00e7\u00f5es Gerais  Art. 14. Na Lei Or\u00e7ament\u00e1ria anual para o exerc\u00edcio de 2022, a discrimina\u00e7\u00e3o da despesa para os Or\u00e7amentos Fiscais e da Seguridade Social far-se-\u00e1 o seguinte desdobramento:  DESPESAS CORRENTES  Despesas de Custeio Transfer\u00eancias Correntes  DESPESAS DE CAPITAL Investimentos Invers\u00f5es Financeiras Transfer\u00eancias de Capital  Art. 15. A Secretaria Municipal de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e habita\u00e7\u00e3o publicar\u00e1 junto com a Lei Or\u00e7ament\u00e1ria os Quadros de Detalhamento da Despesa - QDD, especificando por projetos e atividades os elementos de despesas e respectivos desdobramentos.  Art. 16. A Lei Or\u00e7ament\u00e1ria incluir\u00e1, dentre outros, demonstrativos:  I \u2013 das receitas, obedecendo aos dispositivos do art. 2\u00ba, \u00a7 1\u00ba da Lei Federal n\u00ba. 4.320, de 17 de mar\u00e7o de 1964;  II \u2013 o da natureza da despesa para cada \u00f3rg\u00e3o; e  III \u2013 o da despesa por fonte de recurso para cada \u00f3rg\u00e3o.  Par\u00e1grafo \u00danico - As propostas modificativas no projeto de Lei Or\u00e7ament\u00e1ria, bem como nos projetos de cr\u00e9ditos adicionais, ser\u00e3o apresentadas com as formas, os n\u00edveis de detalhamento, os demonstrativos e as informa\u00e7\u00f5es estabelecidas para o or\u00e7amento nesta Lei, especialmente nos incisos anteriores deste artigo.  Art. 17. Constar\u00e1 no Projeto de Lei Or\u00e7ament\u00e1ria, dota\u00e7\u00f5es espec\u00edficas de transfer\u00eancia de recursos para entidades de assist\u00eancia social e educacional cumprindo normas previstas na Lei Federal 4.320\/64 e demais Legisla\u00e7\u00e3o pertinentes.  Par\u00e1grafo \u00danico \u2013 Dever\u00e1 constar tamb\u00e9m as seguintes autoriza\u00e7\u00f5es;  I \u2013 autoriza\u00e7\u00e3o, por Decreto, a abertura de Cr\u00e9ditos Suplementares que se fizerem necess\u00e1rios, mediante utiliza\u00e7\u00e3o dos recursos definidos no art. 7\u00ba, itens I e II e par\u00e1grafos 1\u00ba, 2\u00ba e 3\u00ba, Art. 42 e Art. 43, par\u00e1grafos 1\u00ba, itens I, II e III e par\u00e1grafos 2\u00ba, 3\u00ba e 4\u00ba respectivamente, ambos da Lei Federal 4.320\/64, de 17 de mar\u00e7o de 1964, at\u00e9 o limite de 50% (cinquenta por cento) do total das despesas fixado nesta Lei para atender a insufici\u00eancia das dota\u00e7\u00f5es or\u00e7ament\u00e1rias dos \u00d3rg\u00e3os da Administra\u00e7\u00e3o e de 100% (cem por cento) para utiliza\u00e7\u00e3o do Excesso de Arrecada\u00e7\u00e3o que se apurar durante o exerc\u00edcio financeiro, nos termos da Lei 4.320\/64;  II \u2013 autoriza\u00e7\u00e3o de at\u00e9 10% (dez por cento) do or\u00e7amento para abertura de cr\u00e9dito especial para cobrir eventuais programas e\/ou ac\u00f5es que possam surgir dentro do exerc\u00edcio de 2022.  Art. 18. A elabora\u00e7\u00e3o do projeto, a aprova\u00e7\u00e3o e a execu\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria de 2022 dever\u00e3o ser realizadas de modo a evidenciar a transpar\u00eancia da gest\u00e3o fiscal, observando-se o princ\u00edpio da publicidade e permitindo-se o amplo acesso da sociedade a todas as informa\u00e7\u00f5es relativas a cada uma dessas etapas, bem como levar em conta a obten\u00e7\u00e3o dos resultados previstos nas metas fiscais.  Art. 19. Em decorr\u00eancia das incertezas quanto as proje\u00e7\u00f5es dos impactos fiscais para o exerc\u00edcio 2022 pela ocorrencia da PANDEMIA devido ao cononav\u00edrus (COVID-19), os demonstrativos das varia\u00e7\u00f5es das Metas Fiscais ser\u00e3o atualizados no envio do Projeto da Lei or\u00e7ament\u00e1ria anual 2022.  Par\u00e1grafo \u00fanico \u2013 Ser\u00e3o acrescentadas A\u00e7\u00f5es or\u00e7ament\u00e1rias no PPA (2022\/2025) de forma ESPEC\u00cdFICA para o enfrentamento do coronav\u00edrus \u2013 COVID-19 e suas muta\u00e7\u00f5es.  Art. 20. No exerc\u00edcio financeiro de 2022, as despesas com pessoal: ativo e inativo e agentes pol\u00edticos dos Poderes Legislativo e Executivo observar\u00e3o os limites estabelecidos na Lei Complementar n\u00b0 101, de 04 de maio de 2000 (Lei de Responsabilidade Fiscal).  Par\u00e1grafo Primeiro \u2013 As despesas com pessoal, agentes pol\u00edticos e encargos sociais ser\u00e3o or\u00e7ados segundo os valores empenhados por r\u00fabrica or\u00e7ament\u00e1ria relativa \u00e0 folha de pagamento do m\u00eas de maio de 2021, observados os limites estabelecidos na Lei Complementar n\u00ba. 101\/2000 (Lei de Responsabilidade Fiscal).  Par\u00e1grafo Segundo \u2013 Nos valores or\u00e7ament\u00e1rios com despesas com pessoal estar\u00e3o previstas as varia\u00e7\u00f5es de corre\u00e7\u00e3o monet\u00e1ria das tabelas que fixam os vencimentos dos cargos e salarios dos servidores com base dos \u00edndices apurados de forma acumulativa do  IPCA \u2013 \u00cdndice de Pre\u00e7os ao Consumidor, do exerc\u00edcio 2021, assegurando a atualiza\u00e7\u00e3o data-base no m\u00eas maio\/2022.   Art. 21. Considera-se como receita corrente l\u00edquida o somat\u00f3rio dos recursos ordin\u00e1rios do Tesouro Municipal, proveniente de receitas tribut\u00e1rias de contribui\u00e7\u00f5es, patrimoniais, agropecu\u00e1rias, industriais, servi\u00e7os, transfer\u00eancias correntes e outras receitas tamb\u00e9m correntes.  Art. 22. As emendas ao projeto de Lei do or\u00e7amento anual ou aos projetos que o modifiquem ser\u00e3o admitidos desde que:  I \u2013 sejam compat\u00edveis com o Plano Plurianual e com a presente Lei;  II \u2013 indiquem os recursos necess\u00e1rios, admitidos apenas os provenientes de anula\u00e7\u00e3o de despesa, exclu\u00eddas as que incidem sobre: a) dota\u00e7\u00e3o para pessoal e seus encargos; b) transfer\u00eancias da Uni\u00e3o, Estados, Conv\u00eanios, Opera\u00e7\u00f5es de Cr\u00e9ditos, Contratos, Acordos, Ajustes e Instrumentos similares desde que vinculados \u00e0 programa\u00e7\u00e3o espec\u00edfica; c) despesas referentes a vincula\u00e7\u00f5es constitucionais.  Par\u00e1grafo \u00danico \u2013 N\u00e3o ser\u00e3o admitidas emendas cujos valores se mostrem incompat\u00edveis e insuficientes \u00e0 cobertura das atividades, projetos, metas ou despesas que se pretenda alcan\u00e7ar e desenvolver.  Art. 23. Caso seja necess\u00e1ria a limita\u00e7\u00e3o do empenho das dota\u00e7\u00f5es or\u00e7ament\u00e1rias e da movimenta\u00e7\u00e3o financeira para atingir as metas fiscais desta Lei, as quais ser\u00e3o atualizadas no envio do Projeto da Lei Or\u00e7ament\u00e1ria 2022, e, essa ser\u00e1 feita de forma proporcional ao montante dos recursos alocados para atendimento de outras despesas correntes, investimentos e invers\u00f5es financeiros de cada poder, executadas as transfer\u00eancias e vincula\u00e7\u00f5es constitucionais.  Art. 24. Todas as receitas realizadas pelos \u00f3rg\u00e3os, fundos e entidades integrantes dos or\u00e7amentos fiscais e da seguridade social, inclusive as diretamente arrecadadas e de conv\u00eanios, ser\u00e3o devidamente classificadas e contabilizadas atrav\u00e9s do sistema informatizado de programa\u00e7\u00e3o e execu\u00e7\u00e3o or\u00e7ament\u00e1ria e financeira do munic\u00edpio, no m\u00e1ximo 24 horas ap\u00f3s a ocorr\u00eancia o respectivo ingresso.  Art. 25. S\u00e3o vedados quaisquer procedimentos pelos ordenadores de despesas que viabilizem a execu\u00e7\u00e3o de despesas sem comprovada e suficiente disponibilidade de dota\u00e7\u00e3o or\u00e7ament\u00e1ria.  Art. 26. As unidades respons\u00e1veis pela execu\u00e7\u00e3o dos cr\u00e9ditos or\u00e7ament\u00e1rios e adicionais aprovados processar\u00e3o o empenho da despesa, observados os limites fixados para cada categoria de programa\u00e7\u00e3o e respectivos grupos de despesas, fontes de recursos, modalidades de aplica\u00e7\u00e3o, especificando o elemento de despesa.  Art. 27. As entidades privadas beneficiadas com recursos p\u00fablicos a qualquer t\u00edtulo submeter-se-\u00e1 \u00e0 fiscaliza\u00e7\u00e3o do Poder Concedente com a finalidade de verificar o cumprimento de metas e objetos para os quais receberam os recursos e ter\u00e3o prazo m\u00e1ximo de 90 (noventa) dias para efetuar a presta\u00e7\u00e3o da contas ao org\u00e3o concedente.   Art. 28. O Poder Executivo adotar\u00e1, durante o exerc\u00edcio financeiro de 2022, as medidas que se fizerem necess\u00e1rias, observados os dispositivos legais, para dinamizar, operacionalizar e equilibrar a execu\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual.  Art. 29. Na hip\u00f3tese de o Projeto de Lei Or\u00e7ament\u00e1ria Anual n\u00e3o ter sido devolvido para sans\u00e3o at\u00e9 31 de dezembro de 2021, fica autorizada a execu\u00e7\u00e3o da proposta or\u00e7ament\u00e1ria originalmente encaminhada para os grupos de despesas de pessoal e encargos sociais, juros e encargos da d\u00edvida, amortiza\u00e7\u00e3o da d\u00edvida e para as despesas com transfer\u00eancias constitucionais.  Par\u00e1grafo \u00danico \u2013 Para as demais despesas n\u00e3o especificadas no caput deste artigo, fica autorizada a execu\u00e7\u00e3o \u00e0 raz\u00e3o de 1\/12 (um doze avos) de cada dota\u00e7\u00e3o or\u00e7ament\u00e1ria por m\u00eas.  Art. 30. No Projeto de Lei Or\u00e7ament\u00e1ria, as receitas e despesas ser\u00e3o or\u00e7adas segundo os pre\u00e7os vigentes no m\u00eas de junho de 2021.  \u00a7 1\u00ba - Os valores da receita e da despesa apresentados no projeto de Lei ser\u00e3o atualizados na Lei Or\u00e7ament\u00e1ria, antes do in\u00edcio de sua execu\u00e7\u00e3o para pre\u00e7os de dezembro de 2021, utilizando para tanto, a varia\u00e7\u00e3o do \u00cdndice de Pre\u00e7os ao Consumidor \u2013 IPCA, do Instituto Brasileiro de Geografia e Estat\u00edstica - IBGE ou outro \u00edndice que vier substitu\u00ed-lo, relativo aos meses de maio a dezembro de 2021, inclu\u00eddos os meses extremos do per\u00edodo. \u00a7 2\u00ba - Aos valores atualizados na forma do disposto no par\u00e1grafo anterior poder\u00e3o ainda ser corrigidos durante a execu\u00e7\u00e3o por crit\u00e9rio que vier a ser estabelecido na Lei Or\u00e7ament\u00e1ria, de forma a manter o valor real dos projetos e atividades previstos no or\u00e7amento. \u00a7 3\u00ba - No caso de extin\u00e7\u00e3o e sem substitui\u00e7\u00e3o do \u00cdndice expresso no \u00a7 1\u00ba deste artigo, o Governo Municipal adotar\u00e1 o que tiver de c\u00e1lculo mais pr\u00f3ximo desse.  Art. 31. Esta Lei entra em vigor na data de sua publica\u00e7\u00e3o, surtindo seus efeitos legais retroativo a 1\u00ba (primeiro) de janeiro de 2022, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.           PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, aos 12 dias do m\u00eas de dezembro do ano de 2022.  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  RETIFICA\u00c7\u00c3O DE PORTARIA NA PORTARIA N\u00ba 2.678\/2022 DE 31 DE OUTUBRO DE 2022  ONDE SE L\u00ca:   Art. 1\u00ba. PRORROGAR A CESS\u00c3O da Servidora Municipal, Alynne Ferreira Rocha, Assistente Social, Matr\u00edcula Funcional n\u00ba 2997, ao Poder Executivo do Estado do Tocantins, no per\u00edodo de 01\/01\/2022 at\u00e9 31\/12\/2023, com \u00f4nus para o requisitante.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, retroagindo seus efeitos legais ao dia 01\/01\/2022, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  LEIA-SE:   Art. 1\u00ba. PRORROGAR A CESS\u00c3O da Servidora Municipal, Alynne Ferreira Rocha, Assistente Social, Matr\u00edcula Funcional n\u00ba 2997, ao Poder Executivo do Estado do Tocantins, no per\u00edodo de 01\/01\/2023 at\u00e9 31\/12\/2023, com \u00f4nus para o requisitante.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, surtindo seus efeitos legais a partir do dia 01\/01\/2023, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e Habita\u00e7\u00e3o  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 265\/2022 DE 08 DE DEZEMBRO DE 2022    \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA A SERVIDORA, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.564\/2021;   R   E   S   O   L   V   E  Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria \u00e0 servidora. K\u00e1tia Alves da Silva, Controladora Geral, Matricula Funcional n\u00ba 5316, para participar da II Semana da Controladoria Interna, nos dias 13,14 e 15 de dezembro de 2022 em Palmas \u2013 TO, para cobrir despesas com alimenta\u00e7\u00e3o, o equivalente 2 \u00bd (duas e meia) di\u00e1rias no valor de R$ 875,00 (oitocentos e setenta e cinco reais), mais passagens de ida e volta no valor de R$ 110,00 (cento e dez reais), totalizando o valor de R$ 985,00 (novecentos e oitenta e cinco reais).  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total ao Servidor conforme consta no art. 1\u00ba desta Portaria.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O DE GUARA\u00cd, Estado do Tocantins, aos oito dias do m\u00eas de dezembro do ano de 2022.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e Habita\u00e7\u00e3o  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 266\/2022 DE 12 DE DEZEMBRO DE 2022   \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA A SRA. PREFEITA, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d   A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.564\/2021;   R E S O L V E   Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria a Sra. Maria de F\u00e1tima Coelho Nunes \u2013 Prefeita Municipal de Guara\u00ed-TO, Matricula Funcional n\u00ba 5313, para participar de uma reuni\u00e3o na AGETO \u2013 Ag\u00eancia Tocantinense de Transportes e Obras e no INCRA, no dia 13 de dezembro de 2022 em Palmas \u2013 TO, para cobrir despesas com alimenta\u00e7\u00e3o, o equivalente a \u00bd (meia) di\u00e1ria, no valor de R$ 210,00 (duzentos e dez reais).  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total a Servidora conforme consta no art. 1\u00ba desta Portaria.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O DE GUARA\u00cd, Estado do Tocantins, aos doze dias do m\u00eas de dezembro do ano de 2022.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e Habita\u00e7\u00e3o  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 267\/2022 DE 12 DE DEZENBRO DE 2022   \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA AO MOTORISTA OFICIAL, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d   A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.564\/2021;   R E S O L V E   Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria ao Sr. Gileno Teixeira Coelho, Matr\u00edcula Funcional: 5579, para acompanhar a Prefeita que ir\u00e1 participar de uma reuni\u00e3o na AGETO \u2013 Ag\u00eancia Tocantinense de Transportes e Obras e no INCRA, no dia 13 de dezembro de 2022 em Palmas \u2013 TO, para cobrir despesas com alimenta\u00e7\u00e3o, o equivalente a \u00bd (meia) di\u00e1ria, no valor de R$ 130,00 (cento e trinta reais).  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total ao Servidor conforme consta no art. 1\u00ba desta Portaria.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O, Estado do Tocantins, aos doze dias do m\u00eas de dezembro do ano de 2022.       Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento, Finan\u00e7as e Habita\u00e7\u00e3o  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal\">.<\/a><\/p>\n\n\n\n<p>BAIXAR PDF: <a href=\"https:\/\/guarai.to.gov.br\/portal\/wp-content\/uploads\/2022\/12\/DOM-1507.pdf\">Edi\u00e7\u00e3o Ordin\u00e1ria 1.507 de 12 de dezembro de 2022<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>. BAIXAR PDF: Edi\u00e7\u00e3o Ordin\u00e1ria 1.507 de 12 de dezembro de 2022<\/p>\n","protected":false},"author":28,"featured_media":31680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[197],"class_list":["post-46780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-oficial","tag-diario-oficial","entry"],"_links":{"self":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/46780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=46780"}],"version-history":[{"count":1,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/46780\/revisions"}],"predecessor-version":[{"id":46784,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/46780\/revisions\/46784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/media\/31680"}],"wp:attachment":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=46780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=46780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=46780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}