{"id":50938,"date":"2024-07-08T16:52:43","date_gmt":"2024-07-08T19:52:43","guid":{"rendered":"https:\/\/guarai.to.gov.br\/portal\/?p=50938"},"modified":"2024-07-08T17:10:09","modified_gmt":"2024-07-08T20:10:09","slug":"edicao-ordinaria-1-862-de-08-de-julho-de-2024","status":"publish","type":"post","link":"https:\/\/guarai.to.gov.br\/portal\/2024\/07\/08\/edicao-ordinaria-1-862-de-08-de-julho-de-2024\/","title":{"rendered":"Edi\u00e7\u00e3o Ordin\u00e1ria 1.862 de 08 de julho de 2024"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><\/figure><div class=\"wp-block-media-text__content\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<p><a href=\"http:\/\/PORTARIA N\u00ba 3.199\/2024 DE 05 DE JULHO DE 2024   \u201cNOMEIA FISCAL DE OBRAS, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS\u201d.  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso das atribui\u00e7\u00f5es que lhe confere o art. 91, IX, da Lei Org\u00e2nica do Munic\u00edpio de Guara\u00ed;  R E S O L V E  Art. 1\u00ba. NOMEAR o Sr. Ronaldo Lansarin Bertamoni, como respons\u00e1vel pela fiscaliza\u00e7\u00e3o da instala\u00e7\u00e3o do sistema de ilumina\u00e7\u00e3o p\u00fablica em LED, no trecho urbano da BR-153, executada pela empresa Santana e Bandeirante LTDA, inscrita no CNPJ sob o n\u00ba 32.135.853\/0001-27, vinculada ao Contrato n\u00b0 035\/2024, Processo n\u00ba. 548\/2024, Concor\u00eancia P\u00fablica n\u00ba 03\/2024, em conson\u00e2ncia com a Lei de Licita\u00e7\u00f5es e regulamentada pelo Decreto Municipal n\u00ba 717\/2015.  Art. 2\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO E FINAN\u00c7AS DE GUARA\u00cd, Estado do Tocantins, aos cinco dias do m\u00eas de julho do ano de 2024.   Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal PORTARIA N\u00ba 3.200\/2024 DE 05 DE JULHO DE 2024   \u201cDESIGNA FISCAL DE CONTRATOS, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS.\u201d  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso das atribui\u00e7\u00f5es que lhe confere o art. 91, IX, da Lei Org\u00e2nica do Munic\u00edpio de Guara\u00ed;  R E S O L V E  Art. 1\u00ba. DESIGNAR o servidor Jose Sobral Teixeira Junior, como Fiscal de Contratos da instala\u00e7\u00e3o do sistema de ilumina\u00e7\u00e3o p\u00fablica em LED, no trecho urbano da BR-153, executada pela empresa Santana e Bandeirante LTDA, inscrita no CNPJ sob o n\u00ba 32.135.853\/0001-27, vinculada ao Contrato n\u00b0 035\/2024, Processo n\u00ba. 548\/2024, Concorr\u00eancia P\u00fablica n\u00ba 03\/2024, em conson\u00e2ncia com a Lei de Licita\u00e7\u00f5es e regulamentada pelo Decreto Municipal n\u00ba 717\/2015.  Art. 2\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO E FINAN\u00c7AS DE GUARA\u00cd, Estado do Tocantins, aos cinco dias do m\u00eas de julho do ano de 2024.   Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 196\/2024 DE 03 DE JULHO DE 2024   \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA A SERVIDOR MUNICIPAL, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS.\u201d  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.772\/2023;   R E S O L V E  Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria ao servidor municipal, Reginaldo Alves Cunha Junior \u2013 Subsecret\u00e1rio de Obras e Infraestrutura, Matr\u00edcula Funcional n\u00ba 5318, para acompanhar a Sra. Prefeita no encontro com o Governador, na cidade de Palmas \u2013 TO, para cobrir despesas com alimenta\u00e7\u00e3o, equivalente a \u00bd (meia) di\u00e1ria, no valor de R$ 210,00 (duzentos e dez reais).  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total a Servidora conforme consta no art. 1\u00ba desta Portaria.   Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O, Estado do Tocantins, aos tr\u00eas dias do m\u00eas de julho do ano de 2024.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA N\u00ba 3.201\/2024 DE 05 DE JULHO DE 2024   \u201cDISP\u00d5E SOBRE A CESS\u00c3O DE SERVIDORA, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS\u201d.  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso das atribui\u00e7\u00f5es que lhe confere o art. 91, inciso IX, da Lei Org\u00e2nica do Munic\u00edpio de Guara\u00ed e em atendimento ao Oficio n\u00ba 3773\/2024\/PRES\/DG\/SGP, subscrito pelo Tribunal Regional Eleitoral do Tocantins;  R E S O L V E  Art. 1\u00ba. PRORROGAR A CESS\u00c3O da Servidora Municipal, a Sra. Elenize da Silva Martins, Assistente Administrativo efetiva, para o Tribunal Regional Eleitoral do Tocantins, por um ano, com \u00f4nus para o requisitante.   Art. 2\u00ba. DETERMINAR que a Diretoria Municipal de Recursos Humanos providencie os respectivos tr\u00e2mites para que esta Portaria surta seus efeitos legais.  Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, retroagindo seus efeitos legais ao do dia 05\/07\/2024, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO E FINAN\u00c7AS DE GUARA\u00cd, Estado do Tocantins, aos cinco dias do m\u00eas de julho do ano de 2024.   Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 197\/2024 DE 08 DE JULHO DE 2024   \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA A SERVIDORA, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d  A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.772\/2023;   R E S O L V E  Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria a Sra. K\u00e1tia Alves da Silva \u2013 Controladora Geral, Matr\u00edcula Funcional n\u00ba 5316, que ir\u00e1 participar do 2\u00ba Congresso de Contrata\u00e7\u00f5es P\u00fablicas do Nordeste, nos dias 17,18 e 19 de julho, na cidade de Macei\u00f3-AL, para cobrir despesas com alimenta\u00e7\u00e3o, o equivalente a 6 e \u00bd (seis e meia) di\u00e1rias, no valor de R$ 4.680,00 (quatro mil, seiscentos e oitenta reais) mais passagens de ida e volta no valor de R$ 120,00 (cento e vinte reais) totalizando o valor de R$ 4.800,00 (quatro mil e oitocentos reais)  Par\u00e1grafo \u00danico. Considera-se no c\u00f4mputo das di\u00e1rias os dias 14 e 15\/07(ida) e 20 e 21\/07 (volta) devido ao hor\u00e1rio de embarque ser pela madruga.  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total a Servidora conforme consta no art. 1\u00ba desta Portaria.  Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O, Estado do Tocantins, aos oito dias do m\u00eas de julho do ano de 2024.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  PORTARIA DE DI\u00c1RIA N\u00ba 198\/2024 DE 08 DE JULHO DE 2024   \u201cAUTORIZA O PAGAMENTO DE DI\u00c1RIA A SERVIDOR, QUE ESPECIFICA E D\u00c1 OUTRAS PROVID\u00caNCIAS. \u201d   A PREFEITA MUNICIPAL DE GUARA\u00cd, Estado do Tocantins, no uso de suas atribui\u00e7\u00f5es legais e constitucionais e, considerando o que disp\u00f5e a Lei Municipal n\u00ba 006\/2000 e o Decreto Municipal n\u00ba 1.772\/2023;   R E S O L V E   Art. 1\u00ba. AUTORIZAR o pagamento de di\u00e1ria ao Sr. Cleube Roza Lima \u2013 Superintendente de Licita\u00e7\u00e3o, Matr\u00edcula Funcional n\u00ba 0251, que ir\u00e1 participar do 2\u00ba Congresso de Contrata\u00e7\u00f5es P\u00fablicas do Nordeste, nos dias 17,18 e 19 de julho, na cidade de Macei\u00f3-AL, para cobrir despesas com alimenta\u00e7\u00e3o, o equivalente a 6 e \u00bd (seis e meia) di\u00e1rias, no valor de R$ 4.680,00 (quatro mil, seiscentos e oitenta reais) mais passagens de ida e volta no valor de R$ 130,00 (cento e trinta reais) totalizando o valor de R$ 4.810,00 (quatro mil e oitocentos e dez reais)  Par\u00e1grafo \u00danico. Considera-se no c\u00f4mputo das di\u00e1rias os dias 14 e 15\/07(ida) e 20 e 21\/07 (volta) devido ao hor\u00e1rio de embarque ser pela madruga.  Art. 2\u00ba. DETERMINAR que a Tesouraria repasse o valor total a Servidora conforme consta no art. 1\u00ba desta Portaria.  Art. 3\u00ba. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogadas as disposi\u00e7\u00f5es em contr\u00e1rio.  PAL\u00c1CIO PAC\u00cdFICO SILVA, GABINETE DA PREFEITA MUNICIPAL E DO SECRET\u00c1RIO DE ADMINISTRA\u00c7\u00c3O, PLANEJAMENTO, FINAN\u00c7AS E HABITA\u00c7\u00c3O, Estado do Tocantins, aos oito dias do m\u00eas de julho do ano de 2024.  Riavan Santana Barbosa Secret\u00e1rio de Administra\u00e7\u00e3o, Planejamento e Finan\u00e7as  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  EXTRATO DE HOMOLOGA\u00c7\u00c3O E ADJUDICA\u00c7\u00c3O  PREFEITURA MUNICIPAL DE GUARA\u00cd - TO EXTRATO DO TERMO DE ADJUDICA\u00c7\u00c3O E HOMOLOGA\u00c7\u00c3O  CONCORR\u00caNCIA P\u00daBLICA N\u00ba 003\/2024 A Prefeitura Municipal de Guara\u00ed - TO, no uso de suas atribui\u00e7\u00f5es legais, faz saber a todos interessados que aos 03\/07\/2024     foi  ADJUDICADO  e  HOMOLOGADO o resultado da Concorr\u00eancia P\u00fablica n\u00b0. 003\/2024, cujo objeto  Contrata\u00e7\u00e3o de empresa especializada para fornecimento e instala\u00e7\u00e3o de sistema de ilumina\u00e7\u00e3o p\u00fablica em LED, com alimenta\u00e7\u00e3o em energia fotovoltaica, a serem utilizadas no trecho urbano da Rodovia Bel\u00e9m-Bras\u00edlia \u2013 BR-153, a empresa  SANTANA E BANDEIRA LTDA, pessoa Jur\u00eddica de direito privado, inscrita no CNPJ sob o n.\u00ba 32135.853\/0001-27,  com valor Global de  R$ 12.899,990,40 (Doze milh\u00f5es oitocentos e noventa e nove mil, novecentos e noventa reais e quarenta centavos),  foi a vencedora desse certame, nos termos da Ata de Sess\u00e3o de Julgamento.     Guara\u00ed \u2013 TO, 08\/07\/2024.  EXTRATO DO CONTRATO n.\u00ba 035\/2024  CONCORR\u00caNCIA P\u00daBLICA N\u00ba 003\/2024 PROCESSO N\u00ba 548\/2024    Contratante: Prefeitura Municipal de Guara\u00ed - TO  Contratada: SANTANA E BANDEIRA LTDA, inscrita no CNPJ sob o n.\u00ba 32135.853\/0001-27 Objeto: Contrata\u00e7\u00e3o de empresa especializada para fornecimento e instala\u00e7\u00e3o de sistema de ilumina\u00e7\u00e3o p\u00fablica em LED, com alimenta\u00e7\u00e3o em energia fotovoltaica, a serem utilizadas no trecho urbano da Rodovia Bel\u00e9m-Bras\u00edlia \u2013 BR-153. Signat\u00e1rios:  Maria de F\u00e1tima Coelho Nunes                         Lincoln Johnson Bandeira Gomes Data de Assinatura: 04\/07\/2024. Valor da Obra:  R$ 12.899,990,40 (Doze milh\u00f5es oitocentos e noventa e nove mil, novecentos e noventa reais e quarenta centavos).  Maria de F\u00e1tima Coelho Nunes Prefeita Municipal  ORDEM DE IN\u00cdCIO DE SERVI\u00c7O N\u00ba 004\/2024  A PREFEITURA MUNICIPAL DE GUARA\u00cd-TO, inscrito no CNPJ 02.070.548\/0001-33, representado pela Sra. Maria de F\u00e1tima Coelho Nunes, com sede na Av. Bernardo Say\u00e3o, s\/n, Centro, Guara\u00ed\/TO, AUTORIZA a empresa SANTANA E BANDEIRA LTDA, inscrita no CNPJ 32.135.853\/0001-27, localizada na Quadra 104 Norte,  Rua NE, Lote 15, Sala 20, Plano Diretor Norte, Palmas\/TO, dar in\u00edcio aos servi\u00e7os, no prazo m\u00e1ximo de 10 (dez) dias \u00fateis, a execu\u00e7\u00e3o da obra referente ao FORNECIMENTO E INSTALA\u00c7\u00c3O DE SISTEMA DE ILUMINA\u00c7\u00c3O P\u00daBLICA EM LED, COM ALIMENTA\u00c7\u00c3O EM ENERGIA FOTOVOLTAICA, A SEREM UTILIZADAS NO TRECHO URBANO DA RODOVIA BEL\u00c9M-BRAS\u00cdLIA \u2013 BR-153, firmado entre as partes, de acordo o Contrato n\u00ba 035\/2024, firmado em 04 de julho de 2024, objeto da Concorr\u00eancia Eletr\u00f4nica n\u00ba 003\/2024, Processo n\u00ba 548\/2024. Guara\u00ed\/TO, 04 de julho de 2024                      LINCOLN JOHNSON BANDEIRA GOMES                             MARIA DE F\u00c1TIMA COELHO NUNES                          SANTANA E BANDEIRA LTDA                                  PREFEITURA MUNICIPAL DE GUARA\u00cd\/TO                             CNPJ: 32.135.853\/0001-27                                                CNPJ 02.070.548\/0001-33  EXTRATO DO CONTRATO N\u00ba 034\/2024  CONCORR\u00caNCIA P\u00daBLICA N\u00ba 002\/2023 PROCESSO N\u00ba 4311\/2023 \u00d3rg\u00e3o: Prefeitura Municipal de Guara\u00ed - TO. Contratada: ECOLUR - EMPRESA DE COLETA DE LIXO URBANO LTDA, CNPJ\/MF  o n.\u00ba   17.361.393\/0001-61 Objeto: contrata\u00e7\u00e3o de empresa especializada na presta\u00e7\u00e3o de servi\u00e7os de varri\u00e7\u00e3o e limpeza de vias e logradouros p\u00fablicos e coleta de res\u00edduos s\u00f3lidos urbanos (lixo domiciliar e de varri\u00e7\u00e3o) no munic\u00edpio de Guara\u00ed\/TO Signat\u00e1rios: Maria de F\u00e1tima Coelho Nunes                       Adrielle Sousa Le\u00e3o Rodrigues  Data de Assinatura: 01\/07\/2024 Valor: R$: 4.354.456,32 (quatro milh\u00f5es trezentos e cinquenta e quatro mil, quatrocentos e cinquenta e sei mil e trinta e dois reais)  Maria de F\u00e1tima Coelho Nunes  Prefeita Municipal de Guara\u00ed      Portaria-RPPS n\u00ba 034\/2024.  Guara\u00ed TO, 05 de julho de 2024.  \u201cFica Dispensado o Processo Licitat\u00f3rio para a contrata\u00e7\u00e3o de escrit\u00f3rio especializado para o estudo, elabora\u00e7\u00e3o de projeto arquitet\u00f4nico, complementares e executivo para reforma do pr\u00e9dio da nova sede Administrativa do Guara\u00ed Prev\u201d.  A Presidente do Regime Pr\u00f3prio de Previd\u00eancia Social do Munic\u00edpio de Guara\u00ed TO, no uso de suas atribui\u00e7\u00f5es legais, e com fulcro na Lei Federal n\u00ba 14.133\/21, instru\u00e7\u00e3o Normativa \u2013 RPPS n\u00ba 001\/2023 e demais normas pertinentes:   CONSIDERANDO as raz\u00f5es exaradas nos Autos do Processo Administrativo n\u00ba 005\/2024;  CONSIDERANDO ainda a Adjudica\u00e7\u00e3o dada pela Agente de Contrata\u00e7\u00e3o ao objeto do processo de Dispensa de Licita\u00e7\u00e3o n\u00ba 004\/2024;  RESOLVE:  Art. 1\u00ba - Fica Dispensada de Procedimento Licitat\u00f3rio sob o n\u00ba 004\/2024, para a contrata\u00e7\u00e3o da empresa: FORTHE LTDA, CNPJ n\u00ba 15.039.685\/0001-57, estabelecida na Rua 260, 39, quadra72 lote 05 sala 08 \u2013 Setor Leste universit\u00e1rio, Goi\u00e2nia \u2013 GO \u2013 CEP: 74.610-240, para o seguinte objeto:  Contrata\u00e7\u00e3o de escrit\u00f3rio especializado para o estudo, elabora\u00e7\u00e3o de projeto arquitet\u00f4nico, complementares e executivo para reforma do pr\u00e9dio da nova sede Administrativa do Guara\u00ed Prev.  Art. 2\u00ba - Esta portaria entra em vigor na data de sua publica\u00e7\u00e3o, revogando as disposi\u00e7\u00f5es em contr\u00e1rio. . Art. 3\u00ba - Publique-se, Registre-se e Cumpra-se.  Gabinete da Presidente do Fundo Municipal de Previd\u00eancia Social dos Servidores de Guara\u00ed, TO, aos 05 dias do m\u00eas de julho de 2024.  Maria Aparecida dos Santos Sobrinho Presidente do GUARA\u00cc-PREV  DISPENSA DE LICITA\u00c7\u00c3O N\u00ba 004\/2024 \u00d3RDEM DE SERVI\u00c7O  OBJETO: Contrata\u00e7\u00e3o de escrit\u00f3rio especializado para o estudo, elabora\u00e7\u00e3o de projeto arquitet\u00f4nico, complementares e executivo para reforma do pr\u00e9dio da nova sede Administrativa do Guara\u00ed Prev.  Considerando o disposto nos autos, AUTORIZAMOS a empresa: FORTHE LTDA, inscrito no CNPJ n\u00ba 155.039.685\/0001-57, a dar in\u00edcio ao objeto conforme disposto em Contrato e Proposta da Contratada.  Guara\u00ed\/TO, 05 de julho de 2024.  Maria Aparecida dos Santos Sobrinho Presidente do GUARA\u00cd-PREV  FORTHE LTDA CNPJ sob n\u00ba 15.039.685\/0001-57 CONTRATADA  EXTRATO Dispensa de Licita\u00e7\u00e3o N\u00ba 004\/2024 INSTRUMENTO CONTRATUAL n\u00ba 004\/2024  OBJETO: Contrata\u00e7\u00e3o de escrit\u00f3rio especializado para o estudo, elabora\u00e7\u00e3o de projeto arquitet\u00f4nico, complementares e executivo para reforma do pr\u00e9dio da nova sede Administrativa do Guara\u00ed Prev.   CONTRATANTE: REGIME PR\u00d3PRIO DE PREVID\u00caNCIA SOCIAL DO MUNICIPIO DE GUARA\u00cd TO, denominado RPPS, inscrito no CNPJ sob o n\u00ba 26.195.928\/0001-62, Pessoa Jur\u00eddica de Direito P\u00fablico, localizado na&nbsp;Avenida Bernardo Say\u00e3o, S\/N, Central, Guara\u00ed TO, CEP 77.7000-000. CONTRATADA: FORTHE LTDA, devidamente cadastrada no CNPJ sob n\u00ba 15.039.685\/0001-57, situada a estabelecida na Rua 260, 39, quadra72 lote 05 sala 08 \u2013 Setor Leste universit\u00e1rio, Goi\u00e2nia \u2013 GO \u2013 CEP: 74.610-240. RECURSOS OR\u00c7AMENT\u00c1RIOS: FICHA...........................: 000675 \u00d3RG\u00c3O........................: 000006 - FUNDO MUN PREV SOCIAL SERVIDORES GUARA\u00cd UNIDADE.....................: 000024 - FUNDO MUN PREV SOCIAL SERV.GUARAI - GUARAIPREV FUN\u00c7\u00c3O......................: 000009 - PREVID\u00caNCIA SOCIAL SUB-FUN\u00c7\u00c3O.............: 000272 - PREVID\u00caNCIA DO REGIME ESTATUT\u00c1RIO PROGRAMA................: 000024 - PREVID\u00caNCIA SOCIAL - GUARAIPREV PROJETO\/ATIVIDADE: 2.390 - Man Servi\u00e7os Administrativos GUARAIPREV ELEMENTO.................: 4.4.50.51 - OUTROS SERVICOS DE TERCEIROS-PESSOA JURI FONTE DE RECURSO: 1.800.1111.000000 \u2013 RPPS FONTE DE RECURSO: 2.802.0000.000000 - RPPS Valor: R$ 13.000,00 (treze mil reais) PRAZO DE VIG\u00caNCIA:  30 (trinta) dias SIGNAT\u00c1RIOS:  MARIA APARECIDA DOS SANTOS SOBRINHO, Presidente do RPPS, residente nesta Cidade de Guara\u00ed TO  RAMON OLIVEIRA, Empres\u00e1rio, residente na cidade de Goi\u00e2nia \u2013 GO.   MARIA APARECIDA DOS SANTOS SOBRINHO, Presidente do RPPS \u2013 Guara\u00ed TO  HOMOLOGA\u00c7\u00c3O DISPENSA DE LICITA\u00c7\u00c3O - 004\/2024  Ap\u00f3s an\u00e1lise ao Processo referente ao procedimento de contrata\u00e7\u00e3o, Pareceres Jur\u00eddico, de Controle Interno e demais e atos acostados aos Autos, HOMOLOGAMOS o Processo de Dispensa de Licita\u00e7\u00e3o n\u00ba 004\/2024.  Objeto: Objeto: Contrata\u00e7\u00e3o de escrit\u00f3rio especializado para o estudo, elabora\u00e7\u00e3o de projeto arquitet\u00f4nico, complementares e executivo para reforma do pr\u00e9dio da nova sede Administrativa do Guara\u00ed Prev. NOME: FORTHE LTDA, CNPJ n\u00ba 15.039.685\/0001-57, estabelecida na Rua 260, 39, quadra72 lote 05 sala 08 \u2013 Setor Leste universit\u00e1rio, Goi\u00e2nia \u2013 GO \u2013 CEP: 74.610-240.  O Valor adjudicado \u00e9 de: R$ 13.000,00 (treze mil reais). Prazo de Vig\u00eancia: 30 (trinta) dias.  Guara\u00ed, TO, 05 de julho de 2024.  Maria Aparecida dos Santos Sobrinho Presidente do GUARA\u00cc-PREV      JULGAMENTO DE RECURSO ADMINISTRATIVO  Processo n.\u00ba1228\/2024, referente ao Edital do Preg\u00e3o Eletr\u00f4nico n.\u00ba 016\/2024, cujo objeto \u00e9 a escolha da proposta mais vantajosa para a eventual aquisi\u00e7\u00e3o de mobili\u00e1rios, equipamentos de inform\u00e1tica, materiais permanentes e utens\u00edlios hospitalares, para equipar a unidade do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia - SAMU, Secretaria Municipal de Sa\u00fade e seus Departamentos.  Trata o presente do julgamento de Recursos Administrativos interpostos pelas empresas MULTI QUADROS E VIDROS LTDA e MARIA CAMILA BARBOSA DA SILVA-MEI contra a decis\u00e3o da Pregoeira do munic\u00edpio de Guara\u00ed-TO.  1. DOS ARGUMENTOS DA IMPUGNANTE Inconformadas, as recorrentes interpuseram recursos contra a decis\u00e3o proferida pela Pregoeira, conforme os fatos demonstrados. As c\u00f3pias dos recursos administrativos seguem anexadas nos autos, rebatendo contra a decis\u00e3o tomada. As recorrentes apresentaram tempestivamente seus argumentos, conforme regra expressa no Edital. As recorridas MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS ELETR\u00d4NICOS LTDA e J G DA CRUZ JUNIOR apresentaram suas contesta\u00e7\u00f5es aos argumentos das recorrentes.  2. DAS RAZ\u00d5ES DOS RECURSOS ADMINISTRATIVO 2.1. Argumentos da Recorrente MULTI QUADROS E VIDROS LTDA A Recorrente fundamenta sua pe\u00e7a contra a aceita\u00e7\u00e3o e habilita\u00e7\u00e3o da Recorrida J G DA CRUZ JUNIOR, alegado n\u00e3o ter atendido as especifica\u00e7\u00f5es do objeto constante do item 63, de acordo com o Termo de Refer\u00eancia. Em consulta ao CAT\u00c1LOGO OFICIAL DO FABRICANTE, e poss\u00edvel verificar que existem v\u00e1rios tipos de quadros totalmente divergentes e inferiores ao solicitado no EDITAL e sem a informa\u00e7\u00e3o do modelo do produto ofertado fica dif\u00edcil para essa comiss\u00e3o analisar o tipo de material que ser\u00e1 fornecido, ou seja, pode estar ofertando um quadro divergente do descrito no Item 63, estando ent\u00e3o em inconformidade com as especifica\u00e7\u00f5es contidas no edital. Edital este que \u00e9 bem claro quanto as suas especifica\u00e7\u00f5es e poss\u00edveis sans\u00f5es em caso de desacordo, conforme podemos notar no caso em tela. Ap\u00f3s an\u00e1lise do cat\u00e1logo enviado, a falta de informa\u00e7\u00e3o referente ao modelo e o pre\u00e7o ofertado pela licitante, \u00e9 claro que o item que ser\u00e1 entregue n\u00e3o estar\u00e1 a altura e com a qualidade esperada pelo \u00f3rg\u00e3o p\u00fablico. O que deve ser entregue \u00e9 um item inferior e que dificilmente ser\u00e1 identificado no recebimento pelo respons\u00e1vel j\u00e1 que visivelmente s\u00e3o produtos bem parecidos, por\u00e9m de qualidade totalmente inferior. A falha da licitante vencedora n\u00e3o pode ser considerada como uma mera formalidade, j\u00e1 que traz impactos e grandes preju\u00edzos aos cofres p\u00fablicos que receber\u00e1 um produto de proced\u00eancia duvidosa, n\u00e3o atendendo aos requisitos conforme solicitado no edital, sendo at\u00e9 mesmo descart\u00e1vel quando utilizado de forma cont\u00ednua. Qualquer proposta que induza o julgamento a mais de um resultado deve ser DESCLASSIFICADA, n\u00e3o devendo haver em qualquer condi\u00e7\u00e3o tal d\u00favida e aceitar tal proposta vai contraria os princ\u00edpios mencionados na Nova Lei de Licita\u00e7\u00f5es 14.133\/21 no seu art. 5\u00b0 e vai na contram\u00e3o da vincula\u00e7\u00e3o ao instrumento convocat\u00f3rio. Tal atitude n\u00e3o deve ser considerada apesar como uma mera formalidade, tendo em vista o N\u00cdTIDO DESCUMPRIMENTO, no qual a \u00fanica alternativa \u00e9 a sua DESCLASSIFICA\u00c7\u00c3O. Assim argumentou!  2.2. Argumentos da Recorrente MARIA CAMILA BAROBOSA DA SILVA-MEI A Recorrente fundamenta sua pe\u00e7a contra a aceita\u00e7\u00e3o das propostas das empresas MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS ELETR\u00d4NICOS LTDA; LAVOR COMERCIAL DE EQUIPAMENTOS LTDA; LS SERVI\u00c7OS DE INFORM\u00c1TICA E ELETRONICA LTDA e da empresa ORBE SOLU\u00c7\u00d5ES LTDA, alegado n\u00e3o terem atendidos as especifica\u00e7\u00f5es do objeto constante do item 61, de acordo com o Termo de Refer\u00eancia. A licitante MAC COPIADORA E COMERCIO DE EQUIPAMENTOS ELETRONICOS LTDA, cotou o produto Lenovo IdeaPad 1i 82VY000SBR para o lote 61, conforme cat\u00e1logo anexo. No entanto, o notebook ofertado n\u00e3o atende aos requisitos do Termo de Refer\u00eancia. Para atender aos requisitos formais do processo de licita\u00e7\u00e3o, \u00e9 imprescind\u00edvel que o cat\u00e1logo anexo seja apresentado em l\u00edngua portuguesa, atualmente em idioma estrangeiro. Isso assegura a compreens\u00e3o e a acessibilidade das informa\u00e7\u00f5es contidas para todos os participantes do processo licitat\u00f3rio. Contudo, ap\u00f3s uma criteriosa avalia\u00e7\u00e3o do cat\u00e1logo em anexo e das informa\u00e7\u00f5es dispon\u00edveis no site oficial da Lenovo, constatou-se que o produto proposto n\u00e3o corresponde \u00e0s especifica\u00e7\u00f5es t\u00e9cnicas necess\u00e1rias para o item 61 deste processo de licita\u00e7\u00e3o. A licitante LAVOR COMERCIAL DE EQUIPAMENTOS LTDA, para o lote 61, ofertou o produto \u201cACER ACER\u201d, conforme proposta inicial. No entanto, sem especificar o modelo ou refer\u00eancia do produto. A licitante ORBE SOLUCOES LTDA, para o lote 61, ofertou o produto \u201cLENOVO IDEA\u201d, conforme proposta inicial. No entanto, sem especificar o modelo ou refer\u00eancia do produto. A licitante LS SERVICOS DE INFORMATICA E ELETRONICA LTDA, para o lote 61, ofertou o produto \u201cSamsung Galaxy Book2\u201d, conforme proposta inicial. No entanto, sem especificar o modelo ou refer\u00eancia do produto. O termo \u2018Galaxy Book2\u2019 \u00e9 uma linha de notebook da marca e n\u00e3o um modelo. Ressaltamos que a falta de precis\u00e3o em um item em um processo licitat\u00f3rio compromete a integridade do certame, pois impede a transpar\u00eancia para os demais concorrentes e para esta comiss\u00e3o de licita\u00e7\u00e3o. Esta omiss\u00e3o de informa\u00e7\u00f5es essenciais pode resultar em uma s\u00e9rie de implica\u00e7\u00f5es negativas para o processo de licita\u00e7\u00e3o. As licitantes est\u00e3o em desacordo com o edital, em especial ao item 6.1.4, que disp\u00f5e do conte\u00fado da proposta inicial apresentada. E no item 10.4 que esclarece sobre a precis\u00e3o da proposta. A aus\u00eancia dessas especifica\u00e7\u00f5es impede que esta comiss\u00e3o de licita\u00e7\u00e3o realize a devida verifica\u00e7\u00e3o dos modelos nos sites dos fabricantes. Ressaltamos a import\u00e2ncia de que a marca e o modelo dos produtos sejam explicitamente mencionados nas propostas submetidas, em alinhamento com os requisitos mencionados nos itens pertinentes do edital. Assim argumentou!  3. DAS CONTRARRAZ\u00d5ES DOS RECURSOS ADMINISTRATIVO 3.1. Defesa da Recorrida J G DA CRUZ JUNIOR \tA Recorrida J G DA CRUZ JUNIOR se defendeu das alega\u00e7\u00f5es manifestas pela Recorrente MULTI QUADROS E VIDROS LTDA conforme abaixo: \tObviamente por se tratar de um cat\u00e1logo geral da fabricante, nem todos os itens ir\u00e3o atender o que se pede no edital. Mas basta uma simples analise, que ser\u00e1 poss\u00edvel a visualiza\u00e7\u00e3o comprovando que temos itens que atendem em nosso cat\u00e1logo. \tAnexaremos nesta contrarraz\u00e3o, or\u00e7amento referente ao item exigido na TR, com a fabricante, para tais evidencias e afirmamos que estamos dispon\u00edveis, caso o agente de licita\u00e7\u00e3o pe\u00e7a diligencias para comprova\u00e7\u00e3o da mesma. Tamb\u00e9m estar\u00e1 anexado carta oficial da fabricante para conosco, onde comprova que somos um dos distribuidores oficiais do grupo da marca. \tPortanto, o produto ir\u00e1 ser entregue conforme descri\u00e7\u00e3o do TR. A recursante, transcende o limite da legalidade quando afirma: \tMesmo com a apresenta\u00e7\u00e3o de eventual planilha de custos por parte da licitante, a administra\u00e7\u00e3o deve utilizar do seu poder de dilig\u00eancias haja vista que o item ofertado pela vencedora \u00e9 manifestamente inexequ\u00edvel. \tAssim rebateu!  3.2. Defesa da Recorrida MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS LTDA A Recorrida MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS LTDA se defendeu das alega\u00e7\u00f5es manifestas pela Recorrente MARIA CAMILA BAROBOSA DA SILVA-MEI conforme abaixo: Entendemos sem muito esfor\u00e7o, que as raz\u00f5es apresentadas pela licitante MARIA CAMILA BARBOSA DA SILVA 09781869402, n\u00e3o merecem ser acolhidas, sendo improcedentes.  Argumentamos, quanto ao armazenamento, que fora destacado em nosso cat\u00e1logo t\u00e9cnico anexo a plataforma no dia 11.06 que o equipamento suporta upgrade de SSD de 1TB m.2 2242 SSD ou 512GB M.2 2280 SSD, logo subentende-se que as altera\u00e7\u00f5es ser\u00e3o realizadas a fim de cumprir com o pleno atendimento das condi\u00e7\u00f5es edital\u00edcias. Destacamos que, para atendimento ao Termo de Refer\u00eancia, que solicita mem\u00f3ria armazenamento de 480GB a 1000GB, ser\u00e1 feito um upgrade de armazenamento para um SSD de 512GB. J\u00e1 em rela\u00e7\u00e3o a mem\u00f3ria RAM, partimos do mesmo princ\u00edpio destacando em nosso cat\u00e1logo t\u00e9cnico anexo a plataforma no dia 11.06 que o equipamento suporta upgrade at\u00e9 16GB sendo 1 pente de mem\u00f3ria de 8GB soldada ao equipamento e a possibilidade de inclus\u00e3o de mais um pente em seu slot livre. Destacamos que, para atendimento ao Termo de Refer\u00eancia, que solicita mem\u00f3ria superior a 8GB, ser\u00e1 inclu\u00eddo mais um pente de mem\u00f3ria de 4GB em seu slot livre. Cabe ressaltar que o cat\u00e1logo t\u00e9cnico do produto (folder) apresentado por nossa empresa, contempla todas os dados necess\u00e1rios sobre o equipamento proposto, e destacamos ainda que sua complexidade \u00e9 tamanha que \u00e9 disponibilizado e acess\u00edvel a qualquer usu\u00e1rio, o detalhamento completo de todas informa\u00e7\u00f5es incluindo certifica\u00e7\u00f5es do referido produto atrav\u00e9s do link. Para concluir, nota-se que acertada foi a decis\u00e3o desta Comiss\u00e3o Licitante, ao classificar como melhor proposta, a proposta apresentada por nossa empresa \u2013 Mac Copiadora - mantendo a regularidade desse procedimento e garantindo a escolha da melhor proposta. Assim rebateu!  3.3. Defesa doutras Recorridas\t As recorridas LAVOR COMERCIAL DE EQUIPAMENTOS LTDA; LS SERVI\u00c7OS DE INFORM\u00c1TICA E ELETRONICA LTDA e ORBE SOLU\u00c7\u00d5ES LTDA se abstiveram das contrarraz\u00f5es cabida pela pe\u00e7a recursal da Recorrente MARIA CAMILA BAROBOSA DA SILVA-MEI   4. DOS PEDIDOS: 4.1. DA RECORRENTE MULTI QUADROS E VIDROS LTDA Diante de todo o exposto, \u00e9 o presente para requerer que Vossas Senhorias, recebam o presente RECURSO ADMINISTRATIVO, para ao final JULGAR PROCEDENTE com fim de reformar a decis\u00e3o administrativa, desclassificando assim a licitante declarada vencedora que est\u00e1 ofertando um produto de qualidade inferior, e n\u00e3o sabemos como esta renomada comiss\u00e3o de licita\u00e7\u00e3o fez o seu parecer t\u00e9cnico competente para avaliar o atendimento do produto ao termo de refer\u00eancia do edital, afrontando assim os princ\u00edpios da legalidade e isonomia, sendo vedada a inclus\u00e3o de documentos intempestivamente, conforme previsto no par\u00e1grafo 3\u00ba do artigo 43 da lei 8.666\/93, sob pena de grave ofensa aos princ\u00edpios da Administra\u00e7\u00e3o, como tamb\u00e9m aos postulados constitucionais da legalidade, razoabilidade e proporcionalidade.  4.2. DA RECORRENTE MARIA CAMILA BAROBOSA DA SILVA-MEI No m\u00e9rito, se digne Vossa Senhoria a dar provimento ao presente recurso, desclassificando as empresas MAC COPIADORA E COMERCIO DE EQUIPAMENTOS ELETRONICOS LTDA, inscrita no CNPJ 24.501.724\/0001-87, LAVOR COMERCIAL DE EQUIPAMENTOS LTDA, inscrita no CNPJ 31.329.288\/0001-76, LS SERVICOS DE INFORMATICA E ELETRONICA LTDA, inscrita no CNPJ 10.793.812\/0003-57 e ORBE SOLUCOES LTDA, inscrita no CNPJ 49.814.976\/0001-97, no lote 61, pois o modelo do notebook ofertado n\u00e3o atende as exig\u00eancias t\u00e9cnicas do termo de refer\u00eancia.  4.3. DA RECORRIDA J G DA CRUZ JUNIOR E, diante de todo o exposto requer a V. Sas. o conhecimento da presente pe\u00e7a recursal, para julg\u00e1-la totalmente IMPROCEDENTE, dando, assim, continuidade ao procedimento, seguindo \u00e0 adjudica\u00e7\u00e3o do contrato \u00e0 nossa empresa, respeitando o princ\u00edpio da economicidade. N\u00e3o sendo este o entendimento de V. Sa., requer sejam os autos remetidos \u00e0 autoridade superior competente, para que, ap\u00f3s an\u00e1lise dos mesmos, defira o presente pedido, dando seguimento ao processo licitat\u00f3rio, em conformidade com o \u00a7 2\u00b0, do art. 165, da Lei n\u00b0 14.133\/21.  4.4. DA RECORRIDA MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS LTDA Em face das raz\u00f5es que foram devidamente expostas, a contra recorrente requer respeitosamente, que sejam estas contrarraz\u00f5es conhecidas e providas em sua integralidade; Seja mantida a decis\u00e3o do (a) Douto (a) Pregoeira, que declarou a empresa Mac Copiadora e Com\u00e9rcio de Equipamentos Eletr\u00f4nicos Ltda., vencedora do item 61 \u2013 Notebook; devendo o recurso interposto pela empresa MARIA CAMILA BARBOSA DA SILVA 09781869402 ser julgado improcedente.  4. DA AN\u00c1LISE \tAs pe\u00e7as recursais e contrarrazoadas recebidas foram analisadas pela Equipe T\u00e9cnica do \u00d3rg\u00e3o Demandante, qual exarou parecer t\u00e9cnico para que se pudesse fazer julgo, uma vez ser de car\u00e1ter t\u00e9cnico as raz\u00f5es e fundamenta\u00e7\u00f5es, qual se encontra acostada nos autos do processo, e assim manifestou: \tAlega\u00e7\u00e3o da Empresa MULTI QUADROS E VIDROS LTDA: impossibilidade de aferi\u00e7\u00e3o de qual  quadro seria entregue tendo em vista que foi enviado o Cat\u00e1logo pela empresa vencedora, omitindo o modelo\/c\u00f3digo do mesmo.   No entanto, como os quadros no cat\u00e1logo possu\u00edam t\u00edtulo e descritivo, foi poss\u00edvel localizar na an\u00e1lise das propostas, o quadro que preenchia o solicitado no Termo de Refer\u00eancia, por este motivo foi a mesma, aceita.  Todavia, na apresenta\u00e7\u00e3o das Contrarraz\u00f5es, a empresa J G DA CRUZ JUNIOR, confirmou que se trata do quadro que consta no FOLDER com o descritivo: Quadro Branco F\u00f3rmica MDF \u2013 Magn\u00e9tico Laminado Melam\u00ednico que seria entregue. Quadro este que atende as caracter\u00edsticas exigidas no Termo de Refer\u00eancia. Alega\u00e7\u00e3o da Empresa MARIA CAMILA BARBOSA DA SILVA: notebook ofertado pela empresa classificada, n\u00e3o atendia as especifica\u00e7\u00f5es nos quesitos t\u00e9cnicos: Armazenamento e Mem\u00f3ria RAM, uma vez que n\u00e3o documentou que o produto passaria por UPGRADE.  Na an\u00e1lise das propostas atrav\u00e9s do Cat\u00e1logo enviado pela empresa, foi verificado que o produto de entrada realmente n\u00e3o atenderia o solicitado, por\u00e9m como estavam grifadas no FOLDER as escritas que o produto tinha capacidade de UPGRADE de at\u00e9 1TB de armazenamento de at\u00e9 16 GB de mem\u00f3ria RAM, entendem-se que passaria pelo UPGRADE para atendimento ao solicitado no Termo de Refer\u00eancia, desta forma, foi a proposta aceita. Ainda assim, na apresenta\u00e7\u00e3o das Contrarraz\u00f5es, a empresa MAC COPIADORA E COM\u00c9RCIO DE EQUIPAMENTOS LTDA, confirmou que ser\u00e1 feito um upgrade de armazenamento para um SSD de 512GB e que ser\u00e1 incluso mais um pente de mem\u00f3ria 4 GB em seu slot livre, para o atendimento ao Termo de Refer\u00eancia nos notebooks que ser\u00e3o entregues. Desta forma, entendemos que atende ao solicitado no descritivo do Termo de Refer\u00eancia.  5. DESCIS\u00c3O Ante ao exposto, forte em todas as argumenta\u00e7\u00f5es supra, DECIDO: CONHECER os Recursos Administrativos interposto pelas empresas MULTI QUADROS E VIDROS LTDA e MARIA CAMILA BARBOSA DA SILVA-ME, por serem tempestivos. NO M\u00c9RITO, a fim de garantir os princ\u00edpios norteadores da Administra\u00e7\u00e3o P\u00fablica, em especial o da legalidade e o da vincula\u00e7\u00e3o ao instrumento convocat\u00f3rio, que seja mantido a decis\u00e3o da Pregoeira e N\u00c3O DAR PROVIMENTO AOS RECURSOS.   Guara\u00ed\/TO, 08 de julho de 2024.  Wellington de Sousa Silva Gestor Municipal\">.<\/a><\/p>\n\n\n\n<p>BAIXAR PDF: <a href=\"https:\/\/guarai.to.gov.br\/portal\/wp-content\/uploads\/2024\/07\/DOM-1862-4.pdf\">Edi\u00e7\u00e3o Ordin\u00e1ria 1.862 de 08 de julho de 2024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>. BAIXAR PDF: Edi\u00e7\u00e3o Ordin\u00e1ria 1.862 de 08 de julho de 2024<\/p>\n","protected":false},"author":28,"featured_media":31680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[197],"class_list":["post-50938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-oficial","tag-diario-oficial","entry"],"_links":{"self":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/50938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=50938"}],"version-history":[{"count":5,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/50938\/revisions"}],"predecessor-version":[{"id":50951,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/posts\/50938\/revisions\/50951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/media\/31680"}],"wp:attachment":[{"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=50938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=50938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guarai.to.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=50938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}